{"id":4267,"date":"2025-05-21T17:40:32","date_gmt":"2025-05-21T15:40:32","guid":{"rendered":"https:\/\/www.skppsc.ch\/de\/?p=4267"},"modified":"2025-05-22T11:40:52","modified_gmt":"2025-05-22T09:40:52","slug":"blog-statistik","status":"publish","type":"post","link":"https:\/\/www.skppsc.ch\/de\/blog-statistik\/","title":{"rendered":"Glauben Sie nur einer Statistik, die Sie auch selbst verstanden haben"},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\"><p class=\"post-excerpt\">Stellen Sie sich vor, <em>Mark<\/em> hat sehr g\u00fcnstig ein altes Velo an der Velo\u00adb\u00f6rse gekauft, er wollte es aufpeppen, aber es wurde ihm bereits einen Tag nach dem Kauf vor seinem Wohnhaus geklaut. Es war ihm auch kein Trost, dass das fabrikneue E-Bike seines Nachbarn <em>Stefan<\/em> in derselben Nacht aus dem Kellerabteil gestohlen wurde. Immerhin war sein Verlust kleiner.<br>Und denken Sie auch an <em>Jessica,<\/em> die am letzten Wochenende vor einem Club von einer Bande betrunkener Jugendlicher sexuell bel\u00e4stigt wurde, die sich erfolgreich an einen T\u00fcrsteher wenden konnte, der den f\u00fcnf jungen M\u00e4nnern sehr deutlich Clubverbot erteilte.<br>Und verdeutlichen Sie sich drittens folgende Situation: <em>Maja<\/em> hat sich von ihrem Freund getrennt, aber er scheint es nicht akzeptieren zu wollen. Er ruft sie zigmal pro Tag an, l\u00e4sst ihr t\u00e4glich Blumen \u00adschicken und schreibt ihr sogar fast t\u00e4glich Briefe und das schon seit 8\u00a0Wochen! <em>Maja<\/em> ist mit den Nerven am Ende und will dem Stalkingverhalten endlich ein Ende setzen.<\/p>\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Wie haben die vier Personen im Anschluss an das Erlebte reagiert? <\/h2>\n\n\n\n<p><em>Mark<\/em> hat den Verlust mit ein wenig \u00c4rger zur Kenntnis genommen und sich ein neues Velo an der B\u00f6rse besorgt. <\/p>\n\n\n\n<p><em>Stefan <\/em>hat den Diebstahl \u00fcber<a href=\"https:\/\/www.suisse-epolice.ch\/home\" target=\"_blank\" rel=\"noreferrer noopener\"> e-police<\/a> angezeigt und ihn seiner Versicherung gemeldet. Mit dem Versicherungsgeld konnte er sich bereits nach zwei Tagen ein neues E-Bike kaufen.<\/p>\n\n\n\n<p><em>Jessica<\/em> hat sich nach der sexuellen Bel\u00e4stigung und N\u00f6tigung im Club bei der <a href=\"https:\/\/www.opferhilfe-schweiz.ch\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Opferhilfe<\/a> ihres Kantons gemeldet und sich erkundigt, was eine Anzeige genau bedeuten w\u00fcrde. Sie wurde gut beraten, hat sich dann aber dennoch entschlossen, keine Anzeige zu erstatten. <\/p>\n\n\n\n<p><em>Maja<\/em> hat sich nach zwei Monaten Tortur und steigender Angst entschlossen, ihren Ex-Freund bei \u00adihrer Kantonspolizei anzuzeigen. Sie war dann sehr erstaunt, wenn nicht entsetzt, dass ihr Ex-Freund gar nicht angezeigt werden<em> kann.<\/em> Es n\u00fctzte ihr wenig, dass die freundliche Polizistin \u00addarauf hingewiesen hat, dass Stalking wohl bald als Straftatbestand aufgenommen werde, es seien \u00adpolitische Bestrebungen diesbez\u00fcglich im Gang. Sie hat <em>Maja<\/em> sogar erkl\u00e4rt, dass sie zivilrechtlich klagen k\u00f6nne, das sei aber deutlich komplizierter. <br><\/p>\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Was hat das alles denn nun mit Statistik zu tun? <\/h2>\n\n\n\n<p>Bei unseren vier Beispielen haben wir es mit vier \u00dcbergriffen im weitesten Sinne zu tun. Drei von diesen vier \u00fcbergriffigen Handlungen werden auch vom Gesetzgeber als \u00fcbergriffig eingestuft und scheinen somit im Strafgesetzbuch auf und k\u00f6nnen zur Anzeige gebracht werden. Von den drei Personen, die Opfer einer Straftat wurden, hat aber nur eine bei der Polizei Anzeige erstattet. <\/p>\n\n\n\n<p>Statistisch gesehen muss eine Handlung also <strong>erstens von den Betroffenen als subjektiv illegal angesehen werden<\/strong> und <strong>zweitens auch objektiv als illegal betrachtet werden<\/strong> und somit im Straf\u00adgesetzbuch aufscheinen. <strong>Drittens muss die Polizei vom Delikt Kenntnis erlangen,<\/strong> weil eine An\u00adzeige erfolgte und <strong>viertens muss die Anzeige so aufgenommen werden, dass sie den Weg zur Justiz nehmen kann. <\/strong>Der vierte Punkt ist dann nicht erf\u00fcllt, wenn eine Straftat zum Beispiel \u00adverj\u00e4hrt ist oder wenn die ersten Ermittlungen zeigen, dass der Straftatbestand doch nicht erf\u00fcllt ist, weil beispielsweise eine Falschanschuldigung vorliegt (was dann eine andere Anzeige wegen Irref\u00fchrung der Rechtspflege nach sich zieht). <\/p>\n\n\n\n<p>Bei unseren Beispielen hat nur eine der vier Grenz\u00fcberschreitungen Zugang in die Statistik gefunden und dies aus unterschiedlichen Gr\u00fcnden. Dass eine Person eine Straftat nicht anzeigt, hat nicht nur mit der Schwere des Delikts zu tun. Gewiss werden wohl oft kleinere Diebst\u00e4hle oder Beleidigungen nicht angezeigt, weil die Betroffenen sich wenig bis nichts von einer Anzeige versprechen. Umgekehrt kommt es aber auch vor, dass andere Institutionen \u2013 wie typischerweise Versicherungen \u2013 neu Anzeigen bei z.\u2009B. Diebst\u00e4hlen einfordern und deshalb mehr Anzeigen bei Bagatelldelikten erfolgen. <\/p>\n\n\n\n<p>Bei <strong>Offizialdelikten<\/strong> \u2013 also Delikten, die die Polizei bei Kenntnis von Amtes wegen verfolgen muss, verh\u00e4lt es sich ein wenig anders. Dabei ist nicht das <strong>Anzeigeverhalten in der Bev\u00f6lkerung<\/strong> ausschlaggebend, sondern die <strong>Kontrollt\u00e4tigkeit der Polizei <\/strong>selbst. <\/p>\n\n\n\n<p>Und je nach Kontrollschwerpunkten kann dies die Statistik massiv beeinflussen. Setzt ein Polizeikorps beispielsweise ihren Fokus auf die Bek\u00e4mpfung von Online-Delikten im Darknet, hat dies in der Regel eine F\u00fclle von Anzeigen zur Folge. Nat\u00fcrlich w\u00e4ren die kriminellen Handlungen auch passiert, wenn die Polizei sie nicht aufgedeckt h\u00e4tte, aber das erschiene dann in keiner Statistik. <\/p>\n\n\n\n<p>Aber auch schwere Delikte wie Sexualdelikte werden bei weitem nicht immer zur Anzeige gebracht. So genannte <strong>Schamdelikte<\/strong> oder auch <strong>Vier-Augen-Delikte<\/strong> (ohne Sachbeweise oder \u00adZeugen) kommen oft nicht zur Anzeige, weil die Betroffenen sich sch\u00e4men und\/oder weil sie sich keinen Ermittlungserfolg versprechen. Nicht angezeigte Delikte bilden das so genannte <strong>Dunkelfeld der Kriminalit\u00e4t. <\/strong>Das Dunkelfeld kann zwar mit Opferbefragungen erhellt werden, die Delikte \u00abim Dunkeln\u00bb werden jedoch von den beh\u00f6rdlichen Statistiken nicht erfasst. <\/p>\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Fassen wir zusammen <\/h2>\n\n\n\n<p>Damit grenzverletzendes Verhalten Eingang in die polizeiliche Kriminalstatistik findet, muss<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>das Verhalten subjektiv als kriminell erfasst werden; <\/li>\n\n\n\n<li>es auch objektiv \u2013 vom Gesetzgeber \u2013 als illegal gelten; <\/li>\n\n\n\n<li>Das Geschehen angezeigt oder von den Strafverfolgungsbeh\u00f6rden geahndet werden und schlussendlich<\/li>\n\n\n\n<li>polizeilich so ermittelt werden, dass das Geschehene der Justiz zur Beurteilung \u00fcbergeben werden kann.<\/li>\n<\/ul>\n\n\n\n<p>Jede kriminelle Handlung, die schlussendlich in die H\u00e4nde der Justiz \u00fcbergeben wird, wird nun von den Justizbeh\u00f6rden beurteilt. Die Ergebnisse davon fliessen dann in die so genannte <a href=\"https:\/\/www.bfs.admin.ch\/bfs\/de\/home\/statistiken\/kriminalitaet-strafrecht\/erhebungen\/sus.html\" target=\"_blank\" rel=\"noreferrer noopener\">Urteils\u00adstatistik<\/a> ein. \u00dcblicherweise ist die Anzahl verurteilter Delikte kleiner als die Anzahl angezeigter Delikte.<\/p>\n\n\n\n<p>Wir hoffen also, Sie haben die <a href=\"https:\/\/www.bfs.admin.ch\/bfs\/de\/home\/statistiken\/kriminalitaet-strafrecht\/erhebungen\/pks.html\" target=\"_blank\" rel=\"noreferrer noopener\">Polizeiliche Kriminalstatistik<\/a> nun besser verstanden und wissen, dass darin nur ein Teil resp. ein verzerrtes Bild des kriminellen Geschehens abgebildet wird. Um daraus pr\u00e4ventive, politische oder sonstige Massnahmen abzuleiten, muss genau hingeschaut und die Hintergr\u00fcnde der Erfassung immer abgekl\u00e4rt werden!<\/p>\n\n\n<\/div><\/div><div class=\"content-part pdf-download-wrapper\"><div class=\"pdf-download-wrapper\"><a href=\"https:\/\/www.skppsc.ch\/de\/wp-content\/uploads\/sites\/2\/2025\/05\/blog_statistik_de.pdf\" download target=\"_blank\" class=\"pdf-download\">blog_statistik_de.pdf<span class=\"skp-download-pdf pdf-download-icon\"><\/span><\/a><\/div><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\"><\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Stellen Sie sich vor, <em>Mark<\/em> hat sehr g\u00fcnstig ein altes Velo an der Velo\u00adb\u00f6rse gekauft, er wollte es aufpeppen, aber es wurde ihm bereits einen Tag nach dem Kauf vor seinem Wohnhaus geklaut. Es war ihm auch kein Trost, dass das fabrikneue E-Bike seines Nachbarn <em>Stefan<\/em> in derselben Nacht aus dem Kellerabteil gestohlen wurde. Immerhin war sein Verlust kleiner.<br \/>Und denken Sie auch an <em>Jessica,<\/em> die am letzten Wochenende vor einem Club von einer Bande betrunkener Jugendlicher sexuell bel\u00e4stigt wurde, die sich erfolgreich an einen T\u00fcrsteher wenden konnte, der den f\u00fcnf jungen M\u00e4nnern sehr deutlich Clubverbot erteilte.<br \/>Und verdeutlichen Sie sich drittens folgende Situation: <em>Maja<\/em> hat sich von ihrem Freund getrennt, aber er scheint es nicht akzeptieren zu wollen. Er ruft sie zigmal pro Tag an, l\u00e4sst ihr t\u00e4glich Blumen \u00adschicken und schreibt ihr sogar fast t\u00e4glich Briefe und das schon seit 8\u00a0Wochen! <em>Maja<\/em> ist mit den Nerven am Ende und will dem Stalkingverhalten endlich ein Ende setzen.<\/p>\n","protected":false},"author":5,"featured_media":4268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"showSharingButtons":false,"skp-theme-color":"twelve","_subtitle":"","alternative_title":"","seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"","notes":"","redirectToPostId":0,"editor_notices":[],"footnotes":""},"categories":[1,35,104],"topic":[],"class_list":["post-4267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-medienkompetenz","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/4267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/comments?post=4267"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/4267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media\/4268"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media?parent=4267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/categories?post=4267"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/topic?post=4267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}