{"id":4338,"date":"2025-07-08T12:20:01","date_gmt":"2025-07-08T10:20:01","guid":{"rendered":"https:\/\/www.skppsc.ch\/de\/?p=4338"},"modified":"2025-07-08T13:38:47","modified_gmt":"2025-07-08T11:38:47","slug":"wann-soll-ich-anzeige-erstatten-einblick-in-die-arbeit-der-kantonspolizei-bern","status":"publish","type":"post","link":"https:\/\/www.skppsc.ch\/de\/wann-soll-ich-anzeige-erstatten-einblick-in-die-arbeit-der-kantonspolizei-bern\/","title":{"rendered":"\u00abWann soll ich Anzeige erstatten?\u00bb \u2013 Einblick in die Arbeit der Kantonspoli..."},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\"><p class=\"post-excerpt\">Die Schweizerische Kriminalpr\u00e4vention (SKP) ist die nationale Fachstelle f\u00fcr kriminalpr\u00e4ventive Beratung und Vermittlung \u2013 f\u00fcr Beh\u00f6rden ebenso wie f\u00fcr B\u00fcrgerinnen und B\u00fcrger. Immer wieder erreichen uns Fragen rund um das Thema \u00abAnzeige erstatten\u00bb: Wann ist der richtige Zeitpunkt? Was passiert danach? Und bringt eine Anzeige \u00fcberhaupt etwas?\u00a0<\/p>\n\n\n<p>Wir haben mit der Berner Kantonspolizistin Samandra Massarotti gesprochen. Sie arbeitet im Innendienst unter anderem im sogenannten Anzeigeb\u00fcro der Polizeiwache am Waisenhausplatz in der Stadt Bern. Im Interview gibt sie Einblick in ihren Alltag \u2013 und in die Realit\u00e4t hinter einer polizeilichen Anzeige.\u00a0<\/p>\n\n\n\n<p><strong>Frau Massarotti, wie sieht Ihr Aufgabenbereich konkret aus?<\/strong>\u00a0<br>Ich bin seit 2016 Polizistin und mittlerweile Mutter einer kleinen Tochter. Deshalb habe ich vom Frontdienst in die Gruppe Fallbearbeitung, welche mehrheitlich im Innendienst t\u00e4tig ist, gewechselt. Heute bearbeite ich Anzeigen, f\u00fchre Befragungen durch und arbeite an Ermittlungen im Hintergrund. Nat\u00fcrlich vermisse ich es manchmal, draussen im Dienst zu sein, sch\u00e4tze es aber sehr, dass ich Teilzeit im B\u00fcro arbeiten kann.\u00a0<\/p>\n\n\n\n<p><strong>Wie ist das Anzeigeb\u00fcro im zweitgr\u00f6ssten Polizeikorps der Schweiz organisiert?<\/strong>\u00a0<br>Grunds\u00e4tzlich sind wir die erste Anlaufstelle und leiten F\u00e4lle gem\u00e4ss internen Abl\u00e4ufen an die zust\u00e4ndigen Fachstellen weiter oder \u00fcberweisen diese direkt an die Staatsanwaltschaft. Anzeigen k\u00f6nnen durch B\u00fcrgerinnen und B\u00fcrger auch direkt an die Staatsanwaltschaft erfolgen, woraufhin wir wiederum einen Ermittlungsauftrag der Staatsanwaltschaft zur Bearbeitung erhalten.\u00a0<\/p>\n\n\n\n<p>Die Polizeiwache Waisenhaus ist oftmals stark frequentiert: Weil sie zentral in der Stadt Bern liegt, kommen tagt\u00e4glich B\u00fcrgerinnen und B\u00fcrger vorbei, um beispielsweise eine Anzeige zu erstatten. Dabei kann es auch einmal zu l\u00e4ngeren Wartezeiten kommen. Am Schalter werden die Meldungen triagiert und einem unserer drei Anzeigeb\u00fcros zugewiesen. Diese gibt es auf allen unseren \u00fcber 50 Polizeiwachen im Kanton Bern; allerdings unterscheiden sich die \u00d6ffnungszeiten und Anzahl Anzeigeb\u00fcros je nach Standort.\u00a0<\/p>\n\n\n\n<p>Je nach Komplexit\u00e4t kann eine Anzeige mehrere Stunden bis hin zu einem ganzen Tag in Anspruch nehmen. In vielen F\u00e4llen m\u00fcssen zus\u00e4tzliche Informationen eingeholt, Beweismaterial wie Videoaufnahmen gesichert oder weitere Schritte eingeleitet werden.\u00a0<\/p>\n\n\n\n<p><strong>Mit welchen Delikten haben Sie im Anzeigeb\u00fcro am h\u00e4ufigsten zu tun?<\/strong>\u00a0<br>Aus meiner Sicht erhalten wir die meisten Anzeigen im Zusammenhang mit Verm\u00f6gensdelikten wie zum Beispiel Diebstahl sowie Cyberdelikten, wie bspw. Online-Betrug oder Phishing. F\u00e4lle wie Gewaltdelikte hingegen werden h\u00e4ufig direkt vor Ort gemeldet, wo wir sofort reagieren k\u00f6nnen und manchmal der Zeitfaktor entscheidend ist \u2013 vor allem zur Spurensicherung, medizinischen Dokumentation oder Information an die zust\u00e4ndige Staatsanwaltschaft.\u00a0<\/p>\n\n\n\n<p><strong>Kommt es vor, dass Sie bei einer Meldung keine Anzeige erstellen?<\/strong>\u00a0<br>Ja, das kommt vor. In bestimmten F\u00e4llen m\u00f6chten B\u00fcrgerinnen und B\u00fcrger lediglich eine Beobachtung mitteilen oder eine Auskunft einholen, ohne dass ein konkreter strafrechtlicher Tatbestand vorliegt. In solchen Situationen resultiert nicht automatisch eine Anzeige. Gerade bei sogenannten Antragsdelikten liegt es zudem im Ermessen der gesch\u00e4digten Person, ob sie einen Strafantrag stellen m\u00f6chte oder nicht. Ich pers\u00f6nlich nehme mir jeweils gerne die Zeit, um den Betroffenen ihre M\u00f6glichkeiten zu erkl\u00e4ren. Viele Menschen sind mit den rechtlichen Abl\u00e4ufen nicht vertraut \u2013 eine transparente und verst\u00e4ndliche Erkl\u00e4rung hilft, Missverst\u00e4ndnisse zu vermeiden.\u00a0<\/p>\n\n\n\n<p>Dabei kommt es vor, dass B\u00fcrgerinnen und B\u00fcrger, obwohl die Voraussetzungen nicht gegeben sind, auf eine Anzeigeerstellung bestehen. Diese \u00fcberweisen wir dann zur Pr\u00fcfung an die Staatsanwaltschaft, welche entscheidet, wie weiterverfahren wird.\u00a0\u00a0<\/p>\n\n\n\n<p><strong>Was ist mit weniger klaren F\u00e4llen, zum Beispiel Mobbing oder Stalking?<\/strong>\u00a0<br>Ist ein strafrechtlicher Anfangsverdacht vorhanden, nehmen wir die Ermittlungen auf, kl\u00e4ren den Sachverhalt und \u00fcberweisen die Ergebnisse wiederum an die Staatsanwaltschaft. Wir empfehlen Betroffenen grunds\u00e4tzlich, verd\u00e4chtige Vorf\u00e4lle m\u00f6glichst genau zu dokumentieren, beispielsweise sich Datum, Ort, Uhrzeit und Personen, die sie bezeugen k\u00f6nnen, zu notieren. F\u00fcr neuartige oder komplexe Ph\u00e4nomene gibt es bei uns interne Schulungen, Leitf\u00e4den und Checklisten: So k\u00f6nnen wir fundiert und strukturiert beraten und vorgehen.\u00a0<\/p>\n\n\n\n<p><strong>Wie reagieren Betroffene bei sensiblen Themen wie Sextortion? Braucht es da besondere Sensibilit\u00e4t?<\/strong>\u00a0<br>Ich bin oft \u00fcberrascht, wie offen B\u00fcrgerinnen und B\u00fcrger mit ihren F\u00e4llen umgehen \u2013 auch wenn es um sehr pers\u00f6nliche Inhalte geht. Das zeigt, dass sie Vertrauen in unsere Professionalit\u00e4t haben.\u00a0<\/p>\n\n\n\n<p><strong>Viele Delikte passieren heute online. Merken Sie eine Entlastung durch die Online-Anzeige-Plattform \u00abSuisse ePolice\u00bb?<\/strong>\u00a0<br>Nein, eher im Gegenteil. Der Trend zeigt: Es geschehen immer mehr Delikte auch online, was wiederum mehr Anzeigen und vertiefte Abkl\u00e4rungen auch im Cyberraum zur Folge hat.\u00a0 Auch die Polizei ist mit der Anzeige-Plattform \u00abSuisse ePolice\u00bb f\u00fcr bestimmte Deliktsarten online pr\u00e4sent. Manche kommen zur Polizeiwache, erfahren von \u00abSuisse ePolice\u00bb und entscheiden sich dann spontan, die Anzeige von zu Hause aus einzureichen. Erfreulicherweise nutzen viele B\u00fcrgerinnen und B\u00fcrger mittlerweile diese M\u00f6glichkeit und ersparen sich dadurch Wartezeiten in den Anzeigeb\u00fcros, aber auch diese Anzeigen f\u00fchren zu Abkl\u00e4rungen \u2013 und landen dann oftmals bei uns auf dem B\u00fcrotisch. Wir helfen bei Bedarf jedoch immer gerne weiter.\u00a0<\/p>\n\n\n\n<p><strong>K\u00f6nnen Anzeigen auch anonym erfolgen?<\/strong>\u00a0<br>Bei sogenannten Antragsdelikten \u2013 Straftaten, bei denen die Strafverfolgung nur erfolgt, wenn die betroffene Person ausdr\u00fccklich Strafantrag stellt \u2013 ist eine anonyme Anzeige nicht m\u00f6glich. Bei anderen Delikten ist es unter bestimmten Bedingungen denkbar, Angaben zur\u00fcckzuhalten. Ich bespreche jeweils mit den Betroffenen, welche Bedenken sie haben, und vermerke dies im Protokoll. Die Staatsanwaltschaft kann sensible Daten auf Wunsch schw\u00e4rzen; eine absolute Anonymit\u00e4t ist jedoch nicht garantiert.\u00a0<\/p>\n\n\n\n<p><strong>Wie gehen Sie mit Personen um, die besonders aufgebracht oder misstrauisch sind?<\/strong>\u00a0<br>Ich pers\u00f6nlich habe bislang fast nur respektvolle Gespr\u00e4che erlebt. Klar gibt es heikle Situationen, in denen wir froh sind, dass wir nicht allein im B\u00fcro sind.\u00a0 In der Regel besteht jedoch auf Seiten unseres Gegen\u00fcbers ein klares Interesse an unserer Unterst\u00fctzung, sie wird gew\u00fcnscht, das schafft in der Regel eine kooperative Ausgangslage.\u00a0<\/p>\n\n\n\n<p><strong>Betreiben Sie auch Pr\u00e4vention im direkten Kontakt mit Betroffenen?<\/strong>\u00a0<br>Ja, unbedingt. Wenn zum Beispiel jemand Opfer von Online-Betrug wurde, erkl\u00e4ren wir, wie man sich k\u00fcnftig besser sch\u00fctzen kann.\u00a0<\/p>\n\n\n\n<p><strong>Wir danken Ihnen herzlich f\u00fcr das informative Gespr\u00e4ch!\u00a0<\/strong><\/p>\n<\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Die Schweizerische Kriminalpr\u00e4vention (SKP) ist die nationale Fachstelle f\u00fcr kriminalpr\u00e4ventive Beratung und Vermittlung \u2013 f\u00fcr Beh\u00f6rden ebenso wie f\u00fcr B\u00fcrgerinnen und B\u00fcrger. Immer wieder erreichen uns Fragen rund um das Thema \u00abAnzeige erstatten\u00bb: Wann ist der richtige Zeitpunkt? Was passiert danach? Und bringt eine Anzeige \u00fcberhaupt etwas?\u00a0<\/p>\n","protected":false},"author":5,"featured_media":4339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"showSharingButtons":false,"skp-theme-color":"sixteen","_subtitle":"","alternative_title":"","seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"","notes":"","redirectToPostId":0,"editor_notices":[],"footnotes":""},"categories":[1,104,37],"topic":[],"class_list":["post-4338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-news","category-zivilcourage"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/4338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/comments?post=4338"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/4338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media\/4339"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media?parent=4338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/categories?post=4338"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/topic?post=4338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}