{"id":613,"date":"2016-09-09T08:47:08","date_gmt":"2016-09-09T06:47:08","guid":{"rendered":"https:\/\/www.skppsc.ch\/de\/?p=613"},"modified":"2019-09-05T09:51:59","modified_gmt":"2019-09-05T07:51:59","slug":"schenkkreise-gefaehrlich-und-verboten","status":"publish","type":"post","link":"https:\/\/www.skppsc.ch\/de\/schenkkreise-gefaehrlich-und-verboten\/","title":{"rendered":"Schenkkreise: Gef\u00e4hrlich und verboten!"},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\"><div class=\"default-container content-part\">\n<div class=\"inner-padding\">\n<h2 class=\" foreground-primary\">Wie funktioniert ein Schenkkreis?<\/h2>\n<p>Schenkkreise funktionieren nach dem Schneeballsystem. Das bedeutet, dass neu in den Kreis eintretende Personen, diejenigen Mitglieder beschenken, welche sich bereits l\u00e4nger im Kreis befinden. Neumitglieder treten dem Kreis in der Hoffnung bei, zu einem sp\u00e4teren Zeitpunkt ebenfalls beschenkt zu werden. In einen Schenkkreis wird man aufgenommen, sobald man eine bestimmt Einlage leistet. Die Betr\u00e4ge reichen von mehreren hundert bis zu mehreren Tausend Franken. Ist man erst einmal im Kreis aufgenommen, so nimmt man in regelm\u00e4ssigen Abst\u00e4nden an Schenktreffen teil. W\u00e4hrenddessen wird man von der Gruppe motiviert respektive unter Druck gesetzt, neue Mitglieder f\u00fcr den Schenkkreis anzuwerben.<\/p>\n<ol>\n<li>Ein Schenkkreis kann unterschiedlich aufgebaut sein und beispielsweise aus 15 Personen bestehen. Er l\u00e4uft in der Regel \u00fcber vier Hierarchiestufen. Wenn der Teilnehmer in der Mitte (der Initiant\/die Initiantin des jeweiligen Schenkkreises) von den acht Teilnehmenden im \u00e4ussersten Kreis beschenkt wurde, verl\u00e4sst er oder sie den Kreis mit seinem\/ihrem \u00abGeschenk\u00bb, also einem Geldbetrag in f\u00fcnf- bis sechsstelliger H\u00f6he.<\/li>\n<li>Damit das Schenkkreis-System nun weiterlaufen kann, m\u00fcssen die acht Teilnehmenden im \u00e4ussersten Kreis 16 neue Mitglieder finden, welche dieselbe anf\u00e4ngliche Einlage leisten und als Schenkende fungieren.<\/li>\n<li>Der urspr\u00fcngliche Kreis teilt sich nun in zwei neue Kreise zu je 15 Personen mit vier Hierarchiestufen. Die urspr\u00fcnglichen acht Schenkenden aus dem \u00e4ussersten Kreis r\u00fccken nun in den beiden neuen Kreiskernen eine Hierarchiestufe nach oben.<\/li>\n<li>Grunds\u00e4tzlich gelangt man also pro Schenk-Runde eine Hierarchiestufe nach oben. Es dauert so also maximal vier Runden, bis man beschenkt wird. Da sich die Teilnehmenden und die Kreise aber nach jeder Runde verdoppeln, bricht das System schon nach kurzer Zeit zusammen, weil keine neuen Teilnehmer mehr gefunden werden k\u00f6nnen, die Geld in das System hineintragen.<\/li>\n<\/ol>\n<h2 class=\" foreground-primary\">Wie sieht die rechtliche Lage beim Thema Schenkkreis aus?<\/h2>\n<p>Als Teilnehmer\/in eines Schenkkreises macht man sich nicht strafbar, solange man nur eine Einlage leistet und jemanden beschenkt. Wenn man hingegen neue Personen f\u00fcr den Schenkkreis anwirbt und diese im Glauben l\u00e4sst, man bekomme gegen eine kleine Einlage einfach so einen Haufen Geld geschenkt, verst\u00f6sst man gegen das <a href=\"https:\/\/www.admin.ch\/opc\/de\/classified-compilation\/19230017\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">Lotteriegesetz <\/a>(s. <a href=\"http:\/\/servat.unibe.ch\/dfr\/bger\/060331_6P_6-2006.html\" target=\"_blank\" rel=\"noopener noreferrer\">Urteil des Bundesgerichtes 6P.6\/2006 vom 31.03.2006<\/a>).<\/p>\n<p>Gem\u00e4ss der Verordnung zum Bundesgesetz betreffend die Lotterien und die gewerbsm\u00e4ssigen Wetten (LV) sind Lotterien in der Schweiz mit einigen bestimmten Ausnahmen verboten. Das Gesetz definiert eine Lotterie als \u00abVeranstaltung, bei der gegen Leistung eines Einsatzes oder bei Abschluss eines Rechtsgesch\u00e4ftes ein verm\u00f6gensrechtlicher Vorteil als Gewinn in Aussicht gestellt wird, \u00fcber dessen Erwerbung, Gr\u00f6sse oder Beschaffenheit planm\u00e4ssig durch Ziehung von Losen oder Nummern oder durch ein \u00e4hnliches auf Zufall gestelltes Mittel entschieden wird\u00bb (Art. 1 Ziff.2).<\/p>\n<p>Da Schenkkreise als lotterie\u00e4hnliche Unternehmungen betrachtet werden, sind Schenkkreise den Lotterien gesetzlich gleichgestellt. Aus diesem Grund ist das Organisieren und Durchf\u00fchren von Schenkkreisen nicht erlaubt!<\/p>\n<p>Aus den folgenden Gr\u00fcnden r\u00e4t die Schweizerische Kriminalpr\u00e4vention, sich <strong>nicht<\/strong> an Schenkkreisen zu beteiligen:<\/p>\n<ul>\n<li>Sie k\u00f6nnen betr\u00e4chtliche finanzielle Verluste erleiden.<\/li>\n<li>Sie k\u00f6nnen sich strafbar machen, indem Sie gegen das Lotteriegesetz verstossen.<\/li>\n<li>Nicht zuletzt k\u00f6nnen Sie Freunde, Verwandte und Bekannte sch\u00e4digen, indem Sie sie f\u00fcr Schenkkreise anwerben und ihnen falsche finanzielle Versprechungen machen.<\/li>\n<\/ul>\n<p>Spielen Sie stattdessen lieber bei den offiziellen Lotterien mit und hoffen Sie auf ein bisschen Gl\u00fcck!<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Schenkkreise \u00fcben nach wie vor eine grosse Anziehungskraft aus und lassen (vor allem gierige und faule) Menschen vom grossen, leicht verdienten Geld tr\u00e4umen.<\/p>\n","protected":false},"author":7,"featured_media":411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"showSharingButtons":false,"skp-theme-color":"two","_subtitle":null,"alternative_title":null,"seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"","notes":"","redirectToPostId":0,"editor_notices":[],"footnotes":""},"categories":[31],"topic":[27],"class_list":["post-613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betrug","topic-betrug-betrug"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/posts\/613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media\/411"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/media?parent=613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/categories?post=613"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/de\/wp-json\/wp\/v2\/topic?post=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}