{"id":1447,"date":"2020-11-25T10:45:03","date_gmt":"2020-11-25T09:45:03","guid":{"rendered":"https:\/\/www.skppsc.ch\/fr\/?page_id=1447"},"modified":"2026-04-21T16:11:35","modified_gmt":"2026-04-21T14:11:35","slug":"violence-sexuelle-enfants","status":"publish","type":"page","link":"https:\/\/www.skppsc.ch\/fr\/sujets\/violence-sexuelle\/violence-sexuelle-enfants\/","title":{"rendered":"Violence sexuelle envers des enfants"},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\">\n<h2 class=\"wp-block-heading foreground-primary\"> P\u00e9docriminels <\/h2>\n\n\n\n<p> Une erreur d\u2019appr\u00e9ciation revient fr\u00e9quemment dans les d\u00e9bats\u2009: les gens pensent en effet que la plupart des personnes qui abusent d\u2019enfants sont des p\u00e9dophiles. Ce n\u2019est pas le cas. Il existe de nombreux autres motifs. Curiosit\u00e9 perverse, crises personnelles, exercice du pouvoir par des moyens sexuels ou sadisme expliquent pourquoi des gens, en r\u00e8gle g\u00e9n\u00e9rale des hommes, abusent d\u2019enfants.<\/p>\n\n\n<\/div><\/div><div class=\"default-container content-part   \" style=\";\"><div class=\"inner-padding\">\n\n\n<h2 class=\"wp-block-heading foreground-primary\"> P\u00e9dophilie <\/h2>\n\n\n\n<p>  Les p\u00e9dophiles sont des personnes qui se sentent exclusivement attir\u00e9es sexuellement par des enfants. La p\u00e9dophilie est donc \u00e0 la fois une orientation sexuelle et un diagnostic psychiatrique. Elle n\u2019a aucune cons\u00e9quence p\u00e9nale aussi longtemps que la personne ne donne pas suite \u00e0 son attirance sexuelle. Ce n\u2019est que lorsqu\u2019elle commet des actes sexuels avec un enfant qu\u2019elle se rend punissable. <\/p>\n\n\n<\/div><\/div><div class=\"default-container content-part   \" style=\";\"><div class=\"inner-padding\">\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Grooming<\/h2>\n\n\n\n<p>Le <em>grooming<\/em>  d\u00e9signe le fait pour une personne adulte d\u2019entrer en contact avec un mineur dans le but de gagner sa confiance pour commettre des abus ou des actes d\u2019ordre sexuel ou encore l\u2019exploiter sexuellement. Aujourd\u2019hui, cette sollicitation d\u2019enfants se pratique surtout sur Internet. L\u2019objectif des p\u00e9dosexuels est toujours le m\u00eame\u00a0: amener un enfant ou un\u00b7e adolescent\u00b7e \u00e0 pratiquer des actes sexuels sur soi, afin de pouvoir ensuite exercer un chantage avec ces images intimes, faire usage de la contrainte, voire m\u00eame l\u2019amener \u00e0 accepter une rencontre r\u00e9elle pour l\u2019abuser.<\/p>\n\n\n\n<p>Le grooming est un ph\u00e9nom\u00e8ne fr\u00e9quent. Selon les autorit\u00e9s de poursuite p\u00e9nale, il s\u2019\u00e9coule en moyenne trois minutes entre la premi\u00e8re prise de contact d\u2019un p\u00e9dosexuel et le moment o\u00f9 tombe le premier commentaire \u00e0 caract\u00e8re sexuel.<\/p>\n\n\n\n<p><div class=\"video-container\"><div class=\"iframe-container\"><div class=\"video-ratio\" style=\"padding-top:56.2%;\"><\/div><iframe loading=\"lazy\" title=\"Grooming - \u00ab Et vous ? Vous auriez dit oui ? \u00bb\" src=\"https:\/\/www.youtube.com\/embed\/KuU87RZ5CTE?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mode op\u00e9ratoire<\/strong><\/h3>\n\n\n\n<p>Les p\u00e9dosexuels trouvent ce qu\u2019ils cherchent sur les plateformes en ligne fr\u00e9quent\u00e9es et appr\u00e9ci\u00e9es par les enfants et les adolescents : jeux, chats ou offres dans les m\u00e9dias sociaux. C\u2019est l\u00e0 que, la plupart du temps, les proies sont contact\u00e9es par ces personnes, qui se font passer pour des adolescents ou de jeunes adultes. Simulant une vive attention pour leurs victimes, elles gagnent leur confiance en se d\u00e9couvrant avec elles des int\u00e9r\u00eats communs. Les conversations virtuelles se d\u00e9placent tr\u00e8s vite sur le terrain sexuel. Les pr\u00e9dateurs s\u2019y entendent pour se donner l\u2019image du confident id\u00e9al forg\u00e9e \u00e0 coup de compliments et de marques de compr\u00e9hension et d\u2019empathie. Une fois la confiance \u00e9tablie, il peut arriver qu\u2019il y ait des tentatives de chantage ou de contrainte. A cette fin, les auteurs se servent de textes, de photos ou de vid\u00e9os, toutes \u00e0 caract\u00e8re intime, afin de forcer leur victime \u00e0 commettre encore d\u2019autres actes d\u2019ordre sexuel ou \u00e0 l\u2019abuser sexuellement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Victimes<\/strong><\/h3>\n\n\n\n<p>Les p\u00e9dosexuels \u00e0 la recherche de proies ne veulent pas \u00eatre d\u00e9masqu\u00e9s. Ils ont un instinct tr\u00e8s s\u00fbr pour d\u00e9tecter les enfants et les ados d\u00e9laiss\u00e9s. Ainsi, ceux d\u2019entre eux qui re\u00e7oivent trop peu d\u2019attention et d\u2019empathie de la part de leurs proches sont particuli\u00e8rement en p\u00e9ril. A noter que les enfants et les ados bien entour\u00e9s peuvent aussi recevoir des sollicitations. Selon des <a href=\"https:\/\/www.zhaw.ch\/de\/psychologie\/forschung\/medienpsychologie\/mediennutzung\/james\" target=\"_blank\" rel=\"noopener\" title=\"\u00e9tudes\">\u00e9tudes<\/a> (site seulement en allemand) men\u00e9es sur les cas non d\u00e9clar\u00e9s, seule une infime part des victimes mineures concern\u00e9es parlent sans tarder \u00e0 leurs parents ou \u00e0 d\u2019autres personnes adultes des comportements abusifs auxquels elles sont expos\u00e9es sur Internet.<\/p>\n\n\n\n<\/div><\/div><div class=\"full content-part image-wrapper image-1451\"><img width=\"2560\" height=\"1280\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-2560x1280.jpg\" class=\"attachment-skp-large-force-ratio size-skp-large-force-ratio\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-2560x1280.jpg 2560w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-1536x768.jpg 1536w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-2048x1024.jpg 2048w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2020\/11\/sexuelle_uebergriffe_5-1280x640.jpg 1280w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n<\/div><\/div><div class=\"default-container content-part   \" style=\";\"><div class=\"inner-padding\">\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Protection de la jeunesse et pornographie infantile <\/h2>\n\n\n\n<p>Les enfants sont un groupe de population particuli\u00e8rement vuln\u00e9rable et la loi doit donc les prot\u00e9ger tout sp\u00e9cialement, notamment en ce qui concerne leur d\u00e9veloppement sexuel. Pour cette raison, aucune forme de pornographie ne doit \u00eatre rendue accessible aux enfants de moins de 16 ans \u2013 \u00e0 l\u2019\u00e2ge dit de protection de la jeunesse. En outre, des mineurs ne doivent pas \u00eatre utilis\u00e9s pour des productions pornographiques ou pour la prostitution. Les produits pornographiques avec des mineurs sont consid\u00e9r\u00e9s comme de <a href=\"https:\/\/www.skppsc.ch\/fr\/sujets\/violence-sexuelle\/pornographie-illegale\/\">la p\u00e9dopornographie<\/a> et sont d\u2019une mani\u00e8re g\u00e9n\u00e9rale interdits.<\/p>\n\n\n<\/div><\/div><div class=\"default-container content-part   \" style=\";\"><div class=\"inner-padding\">\n\n\n<h2 class=\"wp-block-heading foreground-primary\"> Situation juridique <\/h2>\n\n\n\n<p> Voici une s\u00e9lection des articles les plus importants du Code p\u00e9nal concernant les agressions sexuelles :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a187\" target=\"_blank\"><br>Art. 187 CP<\/a>\u2009: Actes d\u2019ordre sexuel avec des enfants<\/h4>\n\n\n\n<p>Est punissable quiconque entra\u00eene un enfant \u00e0 commettre un acte d\u2019ordre sexuel sur lui-m\u00eame et l\u2019observe, ou m\u00eale celui-ci \u00e0 un acte d\u2019ordre sexuel. Si l\u2019enfant est \u00e2g\u00e9 de moins de 12 ans, la peine inflig\u00e9e est plus \u00e9lev\u00e9e. Ceci concerne aussi bien l\u2019acte d\u2019ordre sexuel commis sur des enfants que la contrainte de devoir regarder un tel acte, quand bien m\u00eame il n\u2019y a pas de contact physique entre l\u2019auteur et la victime. En Suisse, la majorit\u00e9 sexuelle est atteinte \u00e0 l\u2019\u00e2ge de 16 ans. Si la diff\u00e9rence d\u2019\u00e2ge entre les participants \u00e0 des actes d\u2019ordre sexuel est sup\u00e9rieure \u00e0 trois ans et que la personne la plus jeune a moins de 16 ans, la plus \u00e2g\u00e9e est punissable. Quant \u00e0 la d\u00e9finition d\u2019un acte d\u2019ordre sexuel, elle est tr\u00e8s large. Ainsi, embrasser avec la langue constitue d\u00e9j\u00e0 une agression sexuelle si la diff\u00e9rence d\u2019\u00e2ge est sup\u00e9rieure \u00e0 ce que la loi autorise.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a188\" target=\"_blank\" rel=\"noreferrer noopener\">Art. 188 CP<\/a>\u2009: Actes d\u2019ordre sexuel avec des personnes d\u00e9pendantes<\/h4>\n\n\n\n<p>Est punissable celui qui commet un acte d\u2019ordre sexuel avec une personne de 16 \u00e0 18 ans ou l\u2019incite \u00e0 commettre un tel acte en profitant de liens de d\u00e9pendance. Il n\u2019y a donc pas que l\u2019\u00e2ge de la victime qui importe mais aussi la relation de d\u00e9pendance. Cette d\u00e9pendance peut r\u00e9sulter de rapports d\u2019\u00e9ducation, de confiance ou de travail, ou de liens de d\u00e9pendance r\u00e9sultant d\u2019activit\u00e9s sportives, culturelles ou religieuses (entra\u00eeneur, coach, chef, etc.).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a189\" target=\"_blank\">Art. 189 CP<\/a>\u2009: Atteinte et contrainte sexuelles<\/h4>\n\n\n\n<p>Est punissable quiconque commet sur une personne ou lui fait commettre, contre sa volont\u00e9, un acte d\u2019ordre sexuel, ou s\u2019il profite \u00e0 cette fin d\u2019un \u00e9tat de sid\u00e9ration de la personne.<\/p>\n\n\n\n<p>Est \u00e9galement punissable quiconque contraint \u00e0 cette fin une personne en usant de menace ou de violence, en exer\u00e7ant sur elle des pressions d\u2019ordre psychique ou en la mettant hors d\u2019\u00e9tat de r\u00e9sister.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a190\" target=\"_blank\" rel=\"noreferrer noopener\">Art. 190 CP\u2009<\/a>: Viol<\/h4>\n\n\n\n<p>Est punissable quiconque commet sur une personne ou lui fait commettre, contre sa volont\u00e9, un acte sexuel ou un acte analogue qui implique une p\u00e9n\u00e9tration du corps, qu\u2019elle soit orale, vaginale ou anale, ou s\u2019il profite \u00e0 cette fin d\u2019un \u00e9tat de sid\u00e9ration de la personne.<\/p>\n\n\n\n<p>Est \u00e9galement punissable quiconque contraint \u00e0 cette fin une personne en usant de menace ou de violence, en exer\u00e7ant sur elle des pressions d\u2019ordre psychique ou en la mettant hors d\u2019\u00e9tat de r\u00e9sister.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a191\" target=\"_blank\" rel=\"noreferrer noopener\">Art. 191 CP<\/a>\u2009: Actes d\u2019ordre sexuel commis sur une personne incapable de discernement ou de r\u00e9sistance<\/h4>\n\n\n\n<p>La diff\u00e9rence entre l\u2019acte d\u2019ordre sexuel commis sur une personne incapable de discernement ou de r\u00e9sistance et l\u2019atteinte ou contrainte sexuelles ou le viol est que dans le premier cas, l\u2019auteur\u00b7e abuse d\u2019une victime qui est d\u00e9j\u00e0 hors d\u2019\u00e9tat de r\u00e9sister. Cette incapacit\u00e9 pr\u00e9vue \u00e0 l\u2019art. 191 CP peut \u00eatre permanente (par exemple dans le cas d\u2019une maladie psychique) ou passag\u00e8re (dans le cas d\u2019une personne ivre ou inconsciente).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a197\">Art. 197 CP<\/a> : \u00ab\u00a0 Pornographie. Disposition de protection de la jeunesse\u00a0\u00bb<\/h4>\n\n\n\n<p>Il n\u2019est pas permis d\u2019offrir, de montrer ou de rendre accessible de la pornographie \u00e0 une personne de moins de 16 ans.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a191\" target=\"_blank\">Art. 197a CP<\/a>\u2009: Transmission indue d\u2019un contenu non public \u00e0 caract\u00e8re sexuel<\/h4>\n\n\n\n<p>Est punissable quiconque transmet \u00e0 un tiers un contenu priv\u00e9 \u00e0 caract\u00e8re sexuel (image, vid\u00e9o, \u00e9crit, objet), sans le consentement de la personne qui y est identifiable. Ce d\u00e9lit n\u2019est poursuivi que si la victime d\u00e9pose plainte. Il s\u2019agit donc d\u2019un d\u00e9lit sur plainte.<\/p>\n\n\n\n<p>La <strong>porno-vengeance, ou revenge porn, <\/strong>d\u00e9signe la diffusion ou la publication de photos ou de vid\u00e9os intimes sans le consentement de la personne qui y est identifiable. En r\u00e8gle g\u00e9n\u00e9rale, il s\u2019agit d\u2019actes commis pour humilier ou causer du tort \u00e0 cette personne. Les cons\u00e9quences \u00e9motionnelles, sociales et professionnelles sont souvent lourdes pour les victimes. Il s\u2019agit, en outre, d\u2019une forme d\u2019abus num\u00e9rique. La porno-vengeance est un d\u00e9lit punissable en Suisse (art. 197a, al. 1 et 2, CP).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a198\" target=\"_blank\" rel=\"noreferrer noopener\">Art. 198 CP<\/a>\u2009: D\u00e9sagr\u00e9ments d\u2019ordre sexuel<\/h4>\n\n\n\n<p>Le harc\u00e8lement sexuel vise des personnes inopin\u00e9ment confront\u00e9es \u00e0 un acte d\u2019ordre sexuel entrepris. Le harc\u00e8lement peut \u00eatre physique (attouchement involontaire d\u2019attributs sexuels secondaires), verbal (expressions vulgaires ou inconvenantes, remarques sur des parties du corps ou sur la vie sexuelle de la victime) ou par l\u2019\u00e9criture ou l\u2019image. Contrairement aux autres d\u00e9lits sexuels, le harc\u00e8lement sexuel n\u2019est poursuivi que si la victime d\u00e9pose plainte. Il s\u2019agit donc d\u2019un d\u00e9lit sur plainte.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html#a22\">Art. 22 CP<\/a>\u00a0:  Degr\u00e9s de r\u00e9alisation. Punissabilit\u00e9 de la tentative <\/h4>\n\n\n\n<p>Entra\u00eener un enfant \u00e0 commettre des actes d\u2019ordre sexuel est punissable m\u00eame s\u2019il ne s\u2019agit que d\u2019une tentative. Il suffit que l\u2019intention puisse \u00eatre d\u00e9montr\u00e9e.<\/p>\n\n\n<\/div><\/div><div class=\"default-container content-part   \" style=\";\"><div class=\"inner-padding\">\n\n\n<h2 class=\"wp-block-heading foreground-primary\"> Que fait la police\u2009? <\/h2>\n\n\n\n<p>D\u00e8s qu\u2019elle a connaissance de formes s\u00e9v\u00e8res d\u2019agression sexuelle, la police enqu\u00eate d\u2019office. Pour plus d\u2019informations, voir la rubrique \u00ab <a href=\"https:\/\/www.skppsc.ch\/fr\/sujets\/violence-sexuelle\/violence-sexuelle-adultes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Violence sexuelle envers des adultes<\/a> \u00bb.<\/p>\n\n\n\n<p><div class=\"video-container\"><div class=\"iframe-container\"><div class=\"video-ratio\" style=\"padding-top:56.2%;\"><\/div><iframe loading=\"lazy\" title=\"Verdacht auf sexuellen Missbrauch\" src=\"https:\/\/www.youtube.com\/embed\/OpAAm2TV9nk?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div><\/p>\n\n\n\n<\/div><\/div><div class=\"default-container clues content-part children-count-3 children-count-odd\"><div class=\"inner-padding\"><a id=\"tips\"><\/a><h2 class=\"subcontent-main-title foreground-primary foreground-primary\">Comment se prot\u00e9ger?<\/h2><div class=\"clues-inner-table clues-count-odd\"><div class=\"clue-item clues-count-odd clues-count-3 background-faded\"><div class=\"clue en-cas-de-soupcon-dabus-denfant\"><p class=\"clue-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"320\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp1alarmzentrale-640x320.jpg\" class=\"attachment-skp-thumbnail-force-ratio size-skp-thumbnail-force-ratio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp1alarmzentrale-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp1alarmzentrale-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp1alarmzentrale-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp1alarmzentrale.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/p><h3 class=\"clue-title background-primary foreground-title\">En cas de soup\u00e7on d\u2019abus d\u2019enfant<\/h3><ul>\n<li><strong>Si vous avez la certitude ou si vous avez une pr\u00e9somption fond\u00e9e d\u2019un abus d\u2019enfant,<\/strong> prenez sans d\u00e9lai contact avec la police\u2009!<\/li>\n<li><strong>Si vous ne soup\u00e7onnez pas concr\u00e8tement<\/strong> mais supposez seulement que quelque chose ne tourne pas rond dans l\u2019environnement familial ou social d\u2019un enfant, vous pouvez commencer par vous adresser \u00e0 un organisme sp\u00e9cialis\u00e9 ou un centre de conseil. <a href=\"http:\/\/www.sodk.ch\/fr\/domaines\/familles-et-societe\/aide-aux-victimes\/wwwaide-aux-victimesch\/\" target=\"_blank\" rel=\"noopener noreferrer\">L\u2019aide aux victimes<\/a> (<a href=\"tel:+41142\">T\u00e9l. 142<\/a><span style=\"color: initial\">)\u00a0<\/span><span style=\"color: initial\">de votre canton peut vous informer.<\/span><\/li>\n<\/ul>\n<\/div><\/div><div class=\"clue-item clues-count-odd clues-count-3 background-faded\"><div class=\"clue proteger-les-enfants\"><p class=\"clue-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"320\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp2sexuelleuebergriffe-640x320.jpg\" class=\"attachment-skp-thumbnail-force-ratio size-skp-thumbnail-force-ratio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp2sexuelleuebergriffe-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp2sexuelleuebergriffe-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp2sexuelleuebergriffe-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp2sexuelleuebergriffe.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/p><h3 class=\"clue-title background-primary foreground-title\">Prot\u00e9ger les enfants<\/h3><p>Les r\u00e8gles sur les mesures que peut prendre l\u2019enfant pour se prot\u00e9ger s\u2019appliquent aussi au comportement \u00e0 adopter sur Internet.<\/p>\n<p>La meilleure des pr\u00e9ventions consiste \u00e0 expliquer tr\u00e8s t\u00f4t et toujours d\u2019une fa\u00e7on adapt\u00e9e \u00e0 l\u2019\u00e2ge de l\u2019enfant. L\u2019enfant doit savoir\u2026<\/p>\n<ul>\n<li>qu\u2019il y a des gens qui peuvent \u00eatre \u00e0 la fois \u00abgentils et m\u00e9chants\u00bb;<\/li>\n<li>qu\u2019il y a des gens qui, pendant un jeu, passent sans transition \u00e0 l\u2019abus\u2009;<\/li>\n<li>qu\u2019il a le droit de dire \u00abnon\u00bb;<\/li>\n<li>qu\u2019il n\u2019est jamais responsable d\u2019une agression sexuelle car c\u2019est toujours l\u2019adulte qui est responsable.<\/li>\n<\/ul>\n<p>La peur est mauvaise conseill\u00e8re et la confiance en soi est une protection efficace contre les agressions sexuelles\u2009!<\/p>\n<ul>\n<li><strong>Faites prendre conscience \u00e0 votre enfant<\/strong> qu\u2019il est une personne qui peut jusqu\u2019\u00e0 un certain point d\u00e9cider pour elle-m\u00eame.<\/li>\n<li><strong>Dites \u00e0 votre enfant<\/strong> que ce n\u2019est pas l\u00e2che d\u2019avoir peur, de prendre la fuite ou de chercher de l\u2019aide. L\u2019enfant doit se fier \u00e0 son mauvais pressentiment ou \u00e0 sa sensation de mal-\u00eatre. Si, pour une raison quelconque, un enfant trouve une situation louche, il doit partir et aller vers des gens ou des lieux qu\u2019il conna\u00eet.<\/li>\n<li><strong>Faites comprendre \u00e0 votre enfant<\/strong> qu\u2019il peut vous raconter tout ce qui lui arrive. Y compris les histoires qui lui paraissent \u00e9tranges ou inqui\u00e9tantes, ou encore celles qui sont arriv\u00e9es parce qu\u2019il n\u2019avait pas ob\u00e9i (p. ex. en empruntant un autre chemin pour aller \u00e0 l\u2019\u00e9cole). Prenez du temps pour parler avec votre enfant de ce qu\u2019il vit et de ses soucis.<\/li>\n<li><strong>La ponctualit\u00e9 est une vertu\u2009:<\/strong> expliquez \u00e0 votre enfant pourquoi il est important qu\u2019il emprunte toujours le chemin qui a \u00e9t\u00e9 convenu pour aller \u00e0 l\u2019\u00e9cole et qu\u2019il soit autant que possible \u00e0 l\u2019heure \u00e0 la maison, \u00e0 l\u2019\u00e9cole, \u00e0 la garderie, etc.<\/li>\n<li><strong>Manifestez votre int\u00e9r\u00eat et renseignez-vous sur tout ce qui pourrait \u00eatre frappant.<\/strong> Int\u00e9ressez-vous au cercle d\u2019amis et de connaissances de votre enfant et \u00e0 leurs activit\u00e9s communes. Interrogez votre enfant s\u2019il ram\u00e8ne tout \u00e0 coup de nouveaux objets \u00e0 la maison, s\u2019il parle de nouveaux amis sensiblement plus \u00e2g\u00e9s que lui.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"clue-item clues-count-odd clues-count-3 background-faded\"><div class=\"clue sil-est-arrive-quelque-chose-a-votre-enfant-ou-sil-pouvait-lui-arriver-quelque-chose\"><p class=\"clue-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"320\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp3sexuelleuebergriffe-640x320.jpg\" class=\"attachment-skp-thumbnail-force-ratio size-skp-thumbnail-force-ratio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp3sexuelleuebergriffe-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp3sexuelleuebergriffe-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp3sexuelleuebergriffe-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/01\/tipp3sexuelleuebergriffe.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/p><h3 class=\"clue-title background-primary foreground-title\">S\u2019il est arriv\u00e9 quelque chose \u00e0 votre enfant ou s\u2019il pouvait lui arriver quelque chose<\/h3><p>Les r\u00e8gles sur les mesures que peuvent prendre les adultes pour le prot\u00e9ger, s\u2019appliquent aussi au comportement \u00e0 adopter sur Internet.<\/p>\n<ul>\n<li><strong>Si malgr\u00e9 tout quelque chose s\u2019est pass\u00e9 ou devait se passer, il est important de r\u00e9agir de mani\u00e8re r\u00e9fl\u00e9chie.<\/strong> Si un enfant parle d\u2019observations faites, d\u2019exp\u00e9riences (d\u00e9sagr\u00e9ables), d\u2019agressions, de menaces, etc., croyez-le et \u00e9coutez-le attentivement.<\/li>\n<li><strong>F\u00e9licitez-le de s\u2019\u00eatre confi\u00e9 \u00e0 vous.<\/strong> Ne le grondez pas s\u2019il a fait quelque chose de faux. Sans quoi il n\u2019osera plus se confier \u00e0 vous.<\/li>\n<li><strong>Annoncez ces observations concr\u00e8tes ou exp\u00e9riences de votre enfant \u00e0 la police.<\/strong> La police a besoin de conna\u00eetre de tels indices.<\/li>\n<li><strong>Si votre enfant devait ne pas rentrer \u00e0 l\u2019heure habituelle,<\/strong> renseignez-vous sans tarder aupr\u00e8s de sa ma\u00eetresse ou de son ma\u00eetre et de ses amis. Si votre enfant demeure introuvable, adressez-vous sans tarder \u00e0 la police en appelant<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n\n<\/div><\/div><div class=\"full content-part post-name-psc-info-1-2017  post-type-download\"><div class=\"inner-padding\"><p class=\"featured-image download hide-on-mobile\"><a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117frweb.pdf\" download target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-640x905.jpg\" class=\"attachment-skp-thumbnail-keep-ratio size-skp-thumbnail-keep-ratio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-640x905.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-212x300.jpg 212w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-768x1086.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/a><\/p><div class=\"remaining-content\"><h2 class=\"sub-content-title  foreground-primary foreground-primary\">PSC INFO 1 | 2017<\/h2><h3 class=\"sub-content-subtitle \"><\/h3><p>PSC INFO 1|2017 est consacr\u00e9 aux diff\u00e9rentes facettes de la th\u00e9matique \u00abLes enfants et la criminalit\u00e9\u00bb. Outre une br\u00e8ve analyse statistique, qui fait ressortir que les enfants n\u2019entrent pas si souvent en conflit avec la loi que l\u2019on pourrait peut-\u00eatre le penser, la derni\u00e8re \u00e9dition de PSC INFO  donne la parole \u00e0 des sp\u00e9cialistes en mati\u00e8re de protection de l\u2019enfant, de p\u00e9dopsychiatrie, de psychiatrie l\u00e9gale et de travail de pr\u00e9vention. Ce n\u2019est qu\u2019en conjuguant leurs forces et leurs savoirs que la police, la th\u00e9rapie, la pr\u00e9vention et aussi la justice parviendront \u00e0 faire baisser le nombre d\u2019enfants, victimes ou auteurs, dans les statistiques, et \u00e0 veiller, le cas \u00e9ch\u00e9ant, \u00e0 faciliter leur d\u00e9veloppement.<\/p>\n<p><\/p>\n<p class=\"featured-image download mobile-only\"><a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117frweb.pdf\" download target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"905\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-640x905.jpg\" class=\"attachment-skp-thumbnail-keep-ratio size-skp-thumbnail-keep-ratio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-640x905.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-212x300.jpg 212w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr-768x1086.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117fr.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"><\/a><\/p><div class=\"download-bottom-actions \"><a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2017\/03\/skpinfo117frweb.pdf\" download target=\"_blank\" class=\"large skp-icon skp-download-pdf download-icon \" title=\"\"><span class=\"link-text\"><\/span><\/a><\/div><\/div><\/div><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\"> Centres de consultation <\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La fondation\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.kinderschutz.ch\/fr\/\" target=\"_blank\">Protection de l\u2019Enfance Suisse<\/a>\u00a0s\u2019occupe principalement des enfants confront\u00e9s \u00e0 la violence domestique, des abus d\u2019enfants et des violences sexuelles. Vous trouverez des renseignements sur les bases juridiques de la fondation et les campagnes qu\u2019elle m\u00e8ne.<\/li>\n\n\n\n<li>Les centres de consultation de Pro Juventute:<br>Pour les enfants et les jeunes :\u00a0<a href=\"https:\/\/www.147.ch\/fr\/\" target=\"_blank\" rel=\"noopener\" title=\"\">www.147.ch<\/a><br>Pour les adultes :\u00a0<a href=\"https:\/\/www.projuventute.ch\/fr\/conseils-aux-parents\" target=\"_blank\" rel=\"noopener\" title=\"https:\/\/\">www.projuventute.ch\/fr\/conseils-aux-parents<\/a><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.clickandstop.ch\/fr\/page-daccueil-1.html\" target=\"_blank\" rel=\"noopener\" title=\"Clickandstop.ch\">Clickandstop.ch<\/a>, le\u00a0service de signalement national en ligne suisse\u00a0contre la violence sexuelle, vous permet de signaler\u00a0facilement et anonymement\u00a0des contenus\u00a0p\u00e9docriminels.\u00a0<\/li>\n\n\n\n<li><p>Les personnes qui des tendances p\u00e9dophiles et qui souhaitent se faire aider avant de commettre des actes punissables peuvent consulter\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/www.disno.ch\/\" target=\"_blank\">Dis No<\/a>.<\/p><\/li>\n<\/ul>\n\n\n\n<\/div><\/div><div class=\"full content-part image-wrapper image-699\"><img width=\"2560\" height=\"1280\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-2560x1280.jpg\" class=\"attachment-skp-large-force-ratio size-skp-large-force-ratio\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-2560x1280.jpg 2560w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2016\/11\/sexuelleuebergriffe4-1280x640.jpg 1280w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n<\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>La plupart des abus d\u2019enfants sont commis par des proches de la victime. Les auteurs sont en g\u00e9n\u00e9ral des membres de la famille au sens large, des amis de celle-ci, des enseignants ou des entra\u00eeneurs sportifs que les enfants connaissent d\u00e9j\u00e0. Les cas d\u2019enfants enlev\u00e9s par des auteurs qui leur sont totalement inconnus pour \u00eatre ensuite abus\u00e9s sexuellement sont extr\u00eamement rares. Pourtant, beaucoup pensent \u00e0 tort que ce tr\u00e8s petit groupe d\u2019auteurs inconnus constitue les p\u00e9docriminels \u00abtypiques\u00bb.<\/p>\n","protected":false},"author":322,"featured_media":696,"parent":134,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"showSharingButtons":false,"skp-theme-color":"eleven","_subtitle":null,"alternative_title":"","seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"","notes":"","redirectToPostId":0,"skp-further-information":"","hideTile":false,"pageType":"","editor_notices":[],"footnotes":""},"topic":[86],"class_list":["post-1447","page","type-page","status-publish","has-post-thumbnail","hentry","topic-violence-sexuelle-enfants"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/1447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/users\/322"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/comments?post=1447"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/1447\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/media\/696"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/media?parent=1447"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/topic?post=1447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}