{"id":2166,"date":"2024-08-12T08:00:00","date_gmt":"2024-08-12T06:00:00","guid":{"rendered":"https:\/\/www.skppsc.ch\/fr\/?page_id=2166"},"modified":"2026-05-01T12:26:25","modified_gmt":"2026-05-01T10:26:25","slug":"interposez-vous","status":"publish","type":"page","link":"https:\/\/www.skppsc.ch\/fr\/projets\/courage-civique\/interposez-vous\/","title":{"rendered":"Interposez-vous\u2009!"},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\">\n<h3 class=\"wp-block-heading\">Vous y apprendrez<\/h3>\n\n\n\n<p><strong>1. <\/strong>ce qu\u2019est le courage civique, et quelles sont ses implications pour la soci\u00e9t\u00e9,<\/p>\n\n\n\n<p><strong>2. <\/strong>pourquoi il est parfois difficile de faire preuve de courage civique, et<\/p>\n\n\n\n<p><strong>3. <\/strong>ce que vous devez savoir avant de faire preuve de courage civique.<\/p>\n\n\n\n<p>\u00c0 la fin de cette rubrique, vous trouverez des informations compl\u00e9mentaires, des offres de conseil et des adresses, avant tout concernant les sujets <strong>violence domestique, discours de haine, mobbing, racisme, vandalisme<\/strong> et <strong>harc\u00e8lement sexuel.<\/strong><\/p>\n\n\n\n<\/div><\/div><div class=\"default-container content-part replaced-hr\"><div class=\"inner-padding\">\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">1. Le courage civique, qu\u2019est-ce que c\u2019est\u2009?<\/h2>\n\n\n\n<p>L\u2019expression \u00ab\u2009courage civil\u2009\u00bb ou \u00ab\u2009courage civique\u2009\u00bb est en usage depuis le 19<sup>e<\/sup>\u2009\u2009si\u00e8cle et se compose du latin <em>civilis<\/em> (= faisant partie de la cit\u00e9, citoyen) et du mot <em>courage,<\/em> qui vient lui-m\u00eame du latin <em>cor<\/em> (= c\u0153ur). <strong>Faire preuve de courage civique, c\u2019est avoir le courage de s\u2019interposer dans un contexte non guerrier.<\/strong> Il ne s\u2019agit pas du courage du soldat en situation de guerre. Nul besoin donc d\u2019\u00eatre expos\u00e9 \u00e0 de grands p\u00e9rils pour montrer du courage. Sous la contrainte, chacun ou presque agit.<\/p>\n\n\n\n<p>Par contre, le citoyen courageux s\u2019expose d\u00e9lib\u00e9r\u00e9ment \u00e0 un danger d\u00e8s lors qu\u2019il s\u2019agit de pr\u00e9server des relations pacifiques au sein de la soci\u00e9t\u00e9. Attentif, il intervient quand quelqu\u2019un est trait\u00e9 injustement, sans se soucier s\u2019il doit prendre certains risques pour r\u00e9tablir la situation. En pr\u00e9sence de deux personnes qui se disputent, il ne d\u00e9tournera pas les yeux.<\/p>\n\n\n\n<p>Le citoyen sans courage, lui, d\u00e9tourne les yeux, ne prend pas position, n\u2019intervient pas et ne vient pas en aide. Certes, il \u00e9chappe momentan\u00e9ment \u00e0 un certain danger, mais, en fait, il encourage indirectement ces forces au sein de la soci\u00e9t\u00e9 qui finiront par troubler sa propre tranquillit\u00e9.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009Qui ne dit mot consent.\u2009\u00bb<\/p>\n<cite>Cic\u00e9ron, 106\u2009\u2013\u200943 av. J.-C.<\/cite><\/blockquote>\n\n\n\n<p>Or, le danger \u00e0 affronter quand on fait preuve de courage civique, n\u2019est pas <em>a priori<\/em> un danger de mort. La menace est calculable et souvent b\u00e9nigne. <strong>N\u00e9anmoins, il y a lieu d\u2019agir sans pr\u00e9cipitation et de fa\u00e7on proportionn\u00e9e.<\/strong> Si vous voyez dans le bus une vieille dame se faire prendre \u00e0 partie par de jeunes voyous, mieux vaut ne pas vous interposer en agitant votre sac \u00e0 main \u2013 surtout si vous \u00eates vous-m\u00eame octog\u00e9naire. Appelez plut\u00f4t la police sans tarder et avisez les passants de ce qui se passe (voir chap. 3)\u2009!<\/p>\n\n\n\n<p><strong>On pourrait m\u00eame dire qu\u2019une soci\u00e9t\u00e9 dans laquelle <em>on risque sa vie <\/em>en faisant preuve de courage civique est une soci\u00e9t\u00e9 en train de perdre son ordre d\u00e9mocratique.<\/strong> Les m\u00e9tropoles europ\u00e9ennes ont vu \u00e9clore des soci\u00e9t\u00e9s parall\u00e8les \u00e9chappant largement au contr\u00f4le exerc\u00e9 par les organes de l\u2019\u00c9tat de droit\u2009; il n\u2019en va pas autrement dans certains villages \u00e0 l\u2019\u00e9cart du monde o\u00f9 l\u2019on pr\u00e9f\u00e8re r\u00e9gler les probl\u00e8mes entre soi. D\u2019ailleurs les tendances anti\u00add\u00e9mocratiques ne proviennent pas toutes d\u2019en bas, d\u2019une frange radicalis\u00e9e de la population, mais de plus en plus d\u2019en haut, des gouvernements eux-m\u00eames\u2009: en pleine Europe d\u2019aujourd\u2019hui, on est en passe de mettre des minorit\u00e9s \u00e0 l\u2019\u00e9cart, de supprimer l\u2019\u00e9galit\u00e9 des citoyens et de r\u00e9duire les libert\u00e9s\u2009!<\/p>\n\n\n\n<p>Le courage civique a une port\u00e9e politique et participe des droits fondamentaux. Ces droits n\u2019ont pas encore \u00e9t\u00e9 jet\u00e9s par-dessus bord mais ils balancent parfois dangereusement au-dessus de l\u2019ab\u00eeme. D\u2019o\u00f9 l\u2019importance du courage civique\u2009: il intervient toujours <em>avant.<\/em> Avant l\u2019ab\u00eeme de la dictature, plus pr\u00e9cis\u00e9ment. Et apr\u00e8s\u2009? Il reste la r\u00e9sistance dans un \u00c9tat de non-droit. Or, <em>r\u00e9sister,<\/em> au p\u00e9ril de sa vie, est cent fois plus difficile que faire preuve de courage civique\u2009!<\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009Lorsque les nazis sont venus chercher les communistes, je n\u2019ai rien dit\u2009; je n\u2019\u00e9tais pas communiste. Lorsqu\u2019ils ont enferm\u00e9 les sociaux-d\u00e9mocrates, je n\u2019ai rien dit\u2009; je n\u2019\u00e9tais pas social-d\u00e9mocrate. Lorsqu\u2019ils sont venus chercher les syndicalistes, je n\u2019ai rien dit\u2009; je n\u2019\u00e9tais pas syndicaliste. Lorsqu\u2019ils sont venus me chercher, il n\u2019y avait plus personne pour protester.\u2009\u00bb<\/p>\n<cite>Martin Niem\u00f6ller, 1892\u2009\u20131984<\/cite><\/blockquote>\n\n\n\n<p><br>Bien s\u00fbr, le risque z\u00e9ro n\u2019existe pas. M\u00eame en temps de paix et m\u00eame lorsque la d\u00e9mocratie est chose acquise, il peut arriver que l\u2019on laisse des plumes dans un conflit. On apprend parfois que des gens ont \u00e9t\u00e9 rou\u00e9s de coups ou qu\u2019ils sont morts parce qu\u2019ils \u00e9taient intervenus dans un conflit. Ces cas, heureusement rares, ne plaident pas <em>contre<\/em> le courage civique\u2009! Bien au contraire. <strong>Car, en y regardant de plus pr\u00e8s, on constate qu\u2019il y a eu un d\u00e9versement de violence parce que les personnes courageuses ont \u00e9t\u00e9 laiss\u00e9es seules par un attroupement de gens passifs et spectateurs.<\/strong> Peu importe que l\u2019on dise ensuite\u2009: \u00ab\u2009Sa conduite a \u00e9t\u00e9 h\u00e9ro\u00efque\u2009\u00bb, car cette personne n\u2019a jamais recherch\u00e9 l\u2019h\u00e9ro\u00efsme\u2009! Elle aurait pr\u00e9f\u00e9r\u00e9 \u00eatre aid\u00e9e plut\u00f4t que d\u2019\u00eatre laiss\u00e9e en plan.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009Malheureux le pays qui a besoin de h\u00e9ros.\u2009\u00bb<\/p>\n<cite>Bertolt Brecht, 1898\u2009\u20131956, \u00ab\u2009La vie de Galil\u00e9e\u2009\u00bb<\/cite><\/blockquote>\n\n\n\n<p><strong>Mieux vaut donc ne pas arriver au point o\u00f9 l\u2019on a besoin que des individus se sacrifient pour d\u2019autres, simplement afin de d\u00e9fendre les valeurs d\u00e9mocratiques fondamentales ou les droits humains\u2009!<\/strong> Pour ne pas en arriver l\u00e0, il faut naturellement qu\u2019une majorit\u00e9 de gens dans la population ne soient pas seulement th\u00e9oriquement \u00ab\u2009plut\u00f4t favorables\u2009\u00bb \u00e0 ces droits et \u00e0 ces valeurs mais que ceux-ci soient vraiment<em> int\u00e9rioris\u00e9s,<\/em> de fa\u00e7on que n\u2019importe o\u00f9, n\u2019importe quand, toute personne respectueuse de ces droits et de ces valeurs se sente personnellement attaqu\u00e9e lorsque l\u2019on y porte atteinte.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009La justice r\u00e8gne d\u00e8s lors qu\u2019un criminel est accus\u00e9 et condamn\u00e9 tant par ceux qu\u2019il a l\u00e9s\u00e9s que par ceux qu\u2019il n\u2019a pas l\u00e9s\u00e9s.\u2009\u00bb<\/p>\n<cite>Solon, env. 640\u2009\u2013\u2009560 av. J.-C.<\/cite><\/blockquote>\n\n\n\n<p>Quels sont ces valeurs et ces droits\u2009? Ils ont pour noms\u2009:<strong> droit \u00e0 la libert\u00e9, droit \u00e0 l\u2019\u00e9galit\u00e9 et droit \u00e0 l\u2019int\u00e9grit\u00e9 corporelle. Aucun \u00eatre humain ne doit subir de discrimination dans l\u2019exercice de sa profession ou dans sa vie priv\u00e9e, en raison de son sexe, de son origine, de la couleur de sa peau, de son orientation sexuelle, de ses opinions politiques et religieuses ou de toute autre conviction<\/strong> \u2013 selon le principe bien connu du \u00ab\u2009vivre et laisser vivre\u2009\u00bb. Il s\u2019agit de la r\u00e8gle d\u2019or de l\u2019\u00e9thique\u2009: \u00ab\u2009Ce que tu ne veux pas qu\u2019on te fasse, ne le fais pas subir \u00e0 un autre\u2009\u00bb. Au bout du compte, c\u2019est toujours la dignit\u00e9 humaine qui est en jeu.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009Les violations des droits de l\u2019homme d\u2019aujourd\u2019hui sont les causes des conflits de demain.\u2009\u00bb<\/p>\n<cite>Kofi Annan, 1938\u20132018<\/cite><\/blockquote>\n\n\n\n<p>Avant de poursuivre, demandez-vous sans d\u00e9tour\u2009: <strong>\u00ab\u2009Ces valeurs sont-elles aussi les miennes\u2009?\u2009\u00bb<\/strong> Car il en va du fondement m\u00eame du courage civique. Si ces valeurs ne vous importent pas en tant que r\u00e8gles du jeu en soci\u00e9t\u00e9, si cela vous est compl\u00e8tement \u00e9gal de savoir comment votre voisin traite ses enfants, ou que Mme Luthy subit le harc\u00e8lement insidieux de ses coll\u00e8gues et perd peu \u00e0 peu tous ses rep\u00e8res, ou que Basile n\u2019est pas invit\u00e9 \u00e0 la f\u00eate parce qu\u2019il est gay et qu\u2019on ne veut pas d\u2019ennui car on sait que Pierre sera l\u00e0 et qu\u2019il est homophobe\u2026 Bref, si vous \u00eates d\u2019avis que tout cela ne vous regarde pas, \u00e0 quoi bon vous demander de faire preuve de courage civique sur quelque terrain que ce soit.<\/p>\n\n\n\n<p><strong>Pourquoi faire preuve de courage civique\u2009? Parce que vous le voulez, et non pas parce que vous le devez.<\/strong><\/p>\n\n\n\n<\/div><\/div><div class=\"full content-part image-wrapper image-2169\"><img width=\"2560\" height=\"1280\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-2560x1280.jpg\" class=\"attachment-skp-large-force-ratio size-skp-large-force-ratio\" alt=\"\" srcset=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-2560x1280.jpg 2560w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-300x150.jpg 300w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-1024x512.jpg 1024w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-768x384.jpg 768w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-1536x768.jpg 1536w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-2048x1024.jpg 2048w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-640x320.jpg 640w, https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2024\/08\/karten_fr-1280x640.jpg 1280w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n\n<p>Vous avez visionn\u00e9 le petit film du d\u00e9but? Il faut bien s\u00fbr le comprendre de mani\u00e8re symbolique. \u00c0 noter qu\u2019on pourrait se demander pourquoi l\u2019aubergiste n\u2019intervient qu\u2019\u00e0 la fin, lorsque le jeune homme veut fumer, et pas avant, lors du \u00ab\u2009mauvais\u2009\u00bb jeu des messieurs avec leurs cartes noires\u2026<\/p>\n\n\n\n<p>Se pourrait-il que, dans le cas de l\u2019interdiction de fumer, l\u2019aubergiste peut s\u2019appuyer sur une loi clairement formul\u00e9e, alors que les concepts que manient les m\u00e9chants messieurs se situent souvent dans une zone grise du point de vue l\u00e9gal\u2009?<\/p>\n\n\n\n<p>Car, \u00ab\u2009S\u2019agit-il simplement d\u2019une blague avec un Noir, un Chinois et un Arabe, ou est-ce d\u00e9j\u00e0 du racisme\u2009?\u2009\u00bb\u2009; \u00ab\u2009S\u2019agit-il d\u2019une photo un peu g\u00eanante prise lors de la sortie d\u2019entreprise, qu\u2019on \u00e9pingle au tableau d\u2019affichage pour taquiner un coll\u00e8gue sans arri\u00e8re-pens\u00e9e, ou est-ce d\u00e9j\u00e0 du harc\u00e8lement\u2009?\u2009\u00bb\u2009; \u00ab\u2009S\u2019agit-il de deux amoureux qui gravent leur nom dans le bois d\u2019une table sans valeur, ou est-ce d\u00e9j\u00e0 du vandalisme\u2009?\u2009\u00bb\u2009; \u00ab\u2009S\u2019agit-il d\u2019une accolade du chef, content du travail accompli, ou d\u2019une caresse d\u00e9plac\u00e9e, et donc d\u00e9j\u00e0 de harc\u00e8lement sexuel\u2009?\u2009\u00bb <strong>Seuls le contexte et les circonstances permettent de faire pencher la balance d\u2019un c\u00f4t\u00e9 ou de l\u2019autre \u2013 ces questions sont vraiment d\u00e9licates.<\/strong><\/p>\n\n\n\n<p>Concentrons-nous plut\u00f4t sur les aspects qui nous rapprochent de la notion de courage civique, dans le film comme dans la vraie vie. Premi\u00e8rement, le jeune homme est <em>attentif\u2009:<\/em> il va voir, il ne d\u00e9tourne pas les yeux. Deuxi\u00e8mement, il examine la situation pour voir s\u2019il y a effectivement violation des valeurs d\u00e9mocratiques fondamentales. <strong>Troisi\u00e8mement, il tient \u00e0 d\u00e9fendre ces valeurs, il surmonte sa peur et s\u2019interpose en invoquant deux comportements\u2009: le respect et la tol\u00e9rance.<\/strong><\/p>\n\n\n\n<p>Le mot \u00ab\u2009respect\u2009\u00bb (du latin\u2009: regarder en arri\u00e8re) indique que celui qui l\u2019\u00e9prouve ne regarde pas ses propres int\u00e9r\u00eats, mais ceux de l\u2019autre, et que cet autre d\u00e9tient a priori des droits que je suis tenu de respecter et qui s\u2019accordent, ou pas, avec les miens\u2009: voil\u00e0 donc encore une notion d\u00e9mocratique du droit. Ainsi, se comporter en respectant l\u2019autre faciliterait la vie en soci\u00e9t\u00e9, que ce soit sur la route, en famille, en faisant des affaires ou en pratiquant un sport, et les rapports entre les sexes et entre les g\u00e9n\u00e9rations. Pour cela, il faut bien s\u00fbr que le respect ne soit pas pratiqu\u00e9 \u00e0 sens unique, mais dans toutes les directions et par toutes les parties en pr\u00e9sence.<\/p>\n\n\n\n<p><strong>Pourtant, le mot \u00ab\u2009respect\u2009\u00bb est souvent employ\u00e9 \u00e0 tort et \u00e0 travers.<\/strong> Ainsi, un groupe de vingt rockers pr\u00eats \u00e0 en d\u00e9coudre entrent dans un bar en exigeant le respect. Il s\u2019agit en fait d\u2019une d\u00e9monstration de sup\u00e9riorit\u00e9 au cas o\u00f9 on en viendrait aux mains. Pour l\u2019expression \u00ab\u2009montrer du respect\u2009\u00bb, le sous-texte dirait ici\u2009: \u00ab\u2009Nous sommes plus forts, soumets-toi\u2009!\u2009\u00bb. Dans certains groupes de jeunes, notamment ceux issus de l\u2019immigration, il n\u2019est pas rare d\u2019entendre tomber le reproche d\u2019un manque de respect, dans le contexte de la religion ou de la famille\u2009: \u00ab\u2009Tu as offens\u00e9 ma religion\u2009!\u2009\u00bb, ou\u2009: \u00ab\u2009Tu as offens\u00e9 ma m\u00e8re\u2009!\u2009\u00bb. Or, il s\u2019agit souvent d\u2019un pr\u00e9texte justifiant le recours \u00e0 la violence. On voit bien que le respect est invoqu\u00e9 \u00e0 tort dans ces exemples.<\/p>\n\n\n\n<p><strong>Car le respect v\u00e9ritable est toujours mutuel, sans qu\u2019il faille l\u2019imposer par l\u2019intimidation ou par la menace. Le respect v\u00e9ritable est li\u00e9 aux droits humains et tient la dignit\u00e9 humaine en haute estime\u2009!<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009L\u2019estime ne saurait se fonder sur la crainte.\u2009\u00bb<\/p>\n<cite>Marie v. Ebner-Eschenbach, 1830\u2009\u20131916<\/cite><\/blockquote>\n\n\n\n<\/div><\/div><div class=\"default-container content-part replaced-hr\"><div class=\"inner-padding\">\n\n\n\n<p>Il en va de m\u00eame pour la notion de<em> tol\u00e9rance,<\/em> qui d\u00e9signe une attitude positive, mue par l\u2019amour de la libert\u00e9 et attach\u00e9e au principe de l\u2019\u00e9galit\u00e9. Or, la tol\u00e9rance peut tr\u00e8s vite prendre la signification contraire selon le terrain auquel elle s\u2019applique. On verra alors \u00e9clore la notion de \u00ab\u2009tol\u00e9rance z\u00e9ro\u2009\u00bb.<\/p>\n\n\n\n<p><strong>Le mot de tol\u00e9rance vient du verbe latin <em>tolerare,<\/em> qui signifie supporter. Il a pour synonyme la patience ou l\u2019endurance. Or, jusqu\u2019\u00e0 quel point faut-il endurer patiemment\u2009? Les r\u00e9ponses peuvent diverger fortement d\u2019une culture \u00e0 l\u2019autre.<\/strong><\/p>\n\n\n\n<p>Tandis que d\u2019aucuns trouveront intol\u00e9rable de voir une mosqu\u00e9e au beau milieu d\u2019un paysage parsem\u00e9 d\u2019\u00e9glises, d\u2019autres ne supporteront pas de voir un visage de femme souriant en public, sans que \u2013 sans que quoi, au juste\u2009? Les uns demandent que l\u2019on tol\u00e8re leur intol\u00e9rance parce qu\u2019ils croient que c\u2019est la volont\u00e9 divine. Et les autres croient que l\u2019on ne devrait pas tol\u00e9rer si l\u00e9g\u00e8rement la <em>croyance<\/em> en une intol\u00e9rance d\u2019\u00e9manation divine. Con\u00e7u en ces termes, le dialogue est sans issue.<\/p>\n\n\n\n<p><strong>L\u00e0 encore, la solution passe par le plus petit d\u00e9nominateur commun, qui consiste, dans une soci\u00e9t\u00e9 libre, d\u00e9mocratique et bas\u00e9e sur l\u2019\u00c9tat de droit, \u00e0 relier la notion de tol\u00e9rance aux principes de la dignit\u00e9 de la personne et aux droits humains. D\u00e8s lors, tout ce qui y contrevient n\u2019est pas tol\u00e9rable. Tout ce qui y contrevient, conviction religieuse ou pas, ne saurait \u00eatre libre, d\u00e9mocratique et relevant de l\u2019\u00c9tat de droit.<\/strong><\/p>\n\n\n\n<p>Hormis les grandes questions politiques et religieuses, la tol\u00e9rance a un aspect pratique au quotidien\u2009: c\u2019est la g\u00e9n\u00e9rosit\u00e9. <strong>Faire preuve de tol\u00e9rance, c\u2019est \u00e9viter de surr\u00e9agir, de se montrer mesquin et revendicateur.<\/strong> Est-ce bien n\u00e9cessaire d\u2019appeler la police \u00e0 chaque fois que les \u00e9chos de la f\u00eate des voisins se font encore entendre au-del\u00e0 de 23h\u2009? Pourquoi ne pas sonner \u00e0 la porte d\u2019\u00e0 c\u00f4t\u00e9 et boire un petit verre en joyeuse compagnie\u2026 Pourquoi d\u00e9verser son fiel quand quelqu\u2019un n\u2019attend pas son tour dans la file d\u2019attente \u00e0 la boulangerie\u2009? Cette personne ne s\u2019en est peut-\u00eatre pas rendu compte\u2009! Faire preuve de tol\u00e9rance, c\u2019est se vacciner contre l\u2019\u00e9troitesse d\u2019esprit et le r\u00e9flexe de d\u00e9noncer. Avoir pour passe-temps de rep\u00e9rer les personnes mal gar\u00e9es pour les d\u00e9noncer ne fait honneur ni \u00e0 soi-m\u00eame ni \u00e0 la d\u00e9mocratie. Avoir pour habitude de r\u00e9primander ses coll\u00e8gues m\u00e8ne \u00e0 l\u2019isolement social. D\u2019ailleurs, le jeune homme dans le film a d\u2019abord tent\u00e9 de se montrer tol\u00e9rant et ce n\u2019est qu\u2019au troisi\u00e8me incident qu\u2019il s\u2019est lev\u00e9.<\/p>\n\n\n\n<p><strong>En somme\u2009: la tol\u00e9rance s\u2019arr\u00eate lorsque les pr\u00e9jug\u00e9s l\u2019emportent, lorsque le manque d\u2019\u00e9gard se fait syst\u00e9matique et le harc\u00e8lement intentionnel. La tol\u00e9rance s\u2019arr\u00eate aussi lorsque certaines opinions inacceptables s\u2019expriment, qu\u2019il s\u2019agisse de blagues sur les Juifs prof\u00e9r\u00e9es pour se profiler dans un groupe ou de n\u00e9gation de g\u00e9nocide, gliss\u00e9e en passant dans la conversation. Pas de tol\u00e9rance non plus en pr\u00e9sence d\u2019un danger de mort, lorsque l\u2019existence m\u00eame est menac\u00e9e par l\u2019usage de la force. Mais nous avons tous une marge de tol\u00e9rance avant d\u2019en arriver \u00e0 ces extr\u00e9mit\u00e9s. Faisons-en usage\u2009!<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009La tol\u00e9rance, c\u2019est bien. Sauf envers les intol\u00e9rants.\u2009\u00bb<\/p>\n<cite>Wilhelm Busch, 1832\u2009\u20131908<\/cite><\/blockquote>\n\n\n\n<\/div><\/div><div class=\"default-container content-part replaced-hr\"><div class=\"inner-padding\">\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">2. Avoir le courage d\u2019\u00eatre courageux<\/h2>\n\n\n\n<p>Pourquoi est-il si difficile de faire preuve de courage civique\u2009? Pour une part, certes, nous h\u00e9sitons \u00e0 intervenir, car nous nous trouvons dans une zone grise juridique. Peu de personnes osent d\u00e8s lors poser clairement des limites (\u00ab\u2009\u00c7a va trop loin\u2009! \u00c7a suffit\u2009!\u2009\u00bb). Pourtant, malheureusement, m\u00eame lorsque la situation rel\u00e8ve sans ambigu\u00eft\u00e9 du registre violent, lorsqu\u2019une personne allong\u00e9e par terre sans d\u00e9fense se fait rouer de coups, il arrive souvent que les badauds restent plant\u00e9s l\u00e0, le regard fixe, sans r\u00e9agir.<\/p>\n\n\n\n<p>La psychologie sociale avance principalement quatre motifs pouvant expliquer cette passivit\u00e9\u2009:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ignorance pluraliste<\/h3>\n\n\n\n<p>Ce concept d\u00e9signe le ph\u00e9nom\u00e8ne selon lequel des individus qui se joignent \u00e0 un groupe interpr\u00e8tent le plus souvent le comportement (passif) de ce groupe comme \u00e9tant <em>justifi\u00e9<\/em> et s\u2019y conforment donc, m\u00eame s\u2019ils auraient eu eux-m\u00eames une autre appr\u00e9ciation de la situation. Dans le pire des cas, il pourrait arriver que vingt personnes post\u00e9es sur une plage regardent au loin quelqu\u2019un se noyer, chacune de ces personnes pensant que les autres ont de bonnes raisons de ne pas lui venir en aide. Plus le nombre de personnes qui assistent \u00e0 une situation exigeant un secours est important, plus la probabilit\u00e9 que l\u2019une d\u2019entre elles d\u00e9cide d\u2019apporter son aide est faible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diffusion de la responsabilit\u00e9<\/h3>\n\n\n\n<p>Au milieu d\u2019une foule, consciemment ou inconsciemment, chacun sentira faiblir sa part de responsabilit\u00e9 et celle-ci se diluer dans la masse \u2013 surtout lorsque les responsabilit\u00e9s ne sont pas clairement \u00e9tablies. Chaque individu fera donc ce que fait la masse en tablant d\u2019avance sur le fait que la masse saura bien comment agir. Or, sachant que toute situation d\u2019urgence ou de danger exige de redoubler d\u2019attention et de prendre la mesure de la menace avant d\u2019agir, l\u2019ignorance pluraliste et la diffusion de la responsabilit\u00e9 font que, bien souvent, malheureusement, l\u2019individu dans la masse en reste \u00e0 l\u2019observation. C\u2019est l\u2019attroupement de badauds \u00e9bahis incapables de passer \u00e0 l\u2019\u00e9tape suivante\u2009: agir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Peur de se ridiculiser<\/h3>\n\n\n\n<p>Pour beaucoup d\u2019entre nous, agir revient \u00e0 entrer en sc\u00e8ne sous le feu des projecteurs et \u00e0 sortir de l\u2019anonymat de la masse. Un pas que beaucoup ne franchissent pas, par peur de s\u2019exposer et d\u2019attirer l\u2019attention sur eux. Ils craignent de se ridiculiser s\u2019ils venaient, par apr\u00e8s, \u00e0 constater que leur interpr\u00e9tation de la situation \u00e9tait erron\u00e9e ou qu\u2019ils n\u2019\u00e9taient pas \u00e0 la hauteur et qu\u2019ils \u00e9taient donc la ris\u00e9e du public \u2013 le jeune homme dans le film a d\u00fb subir les sarcasmes et les ricanements des habitu\u00e9s des lieux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Peur pour sa vie et pour son int\u00e9grit\u00e9 corporelle<\/h3>\n\n\n\n<p>Beaucoup de personnes h\u00e9sitent \u00e0 s\u2019interposer lors d\u2019une bagarre ou d\u2019un \u00e9change d\u2019injures parce qu\u2019ils craignent de subir eux-m\u00eames des violences physiques. Cela est parfaitement compr\u00e9hensible. Ce qui l\u2019est moins, c\u2019est de passer son chemin comme si de rien n\u2019\u00e9tait, au lieu d\u2019alerter la police et de rester dans les parages pour venir en aide \u00e0 la victime, le cas \u00e9ch\u00e9ant, d\u00e8s que les malfaiteurs auront quitt\u00e9 les lieux.<\/p>\n\n\n\n<p>Afin de contribuer r\u00e9solument au mieux vivre ensemble, il s\u2019agit de surmonter ces quatre types de peurs et de m\u00e9canismes psychiques. Le prochain chapitre d\u00e9crit comment faire pour y parvenir.<\/p>\n\n\n\n<\/div><\/div><div class=\"default-container content-part replaced-hr\"><div class=\"inner-padding\">\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">3. Comment s\u2019interposer au mieux\u2009?<\/h2>\n\n\n\n<p>Bonne nouvelle\u2009:<strong> le courage civique, \u00e7a s\u2019apprend\u2009!<\/strong><\/p>\n\n\n\n<p>Pr\u00e9alable important\u2009: avoir un syst\u00e8me de valeurs stable, ensuite avoir conscience des facteurs socio-psychologiques qui entrent en jeu en pr\u00e9sence d\u2019une menace.<\/p>\n\n\n\n<p>En d\u2019autres termes\u2009: <strong>si tout d\u2019un coup vous r\u00e9alisez que quelqu\u2019un, pr\u00e8s de vous, est attaqu\u00e9 physiquement ou trait\u00e9 injustement et que vous ressentez une peur diffuse, vous pouvez \u00eatre s\u00fbr que cette situation en appelle \u00e0 votre courage civique\u2009!<\/strong><\/p>\n\n\n\n<p>Si, pour vous, ces deux conditions sont r\u00e9unies, vous lirez avec profit les six \u00ab\u2009R\u00e8gles de comportement en cas d\u2019urgence\u2009\u00bb, \u00e0 savoir\u2009:<\/p>\n\n\n<\/div><\/div><div class=\"default-container clues content-part children-count-6 children-count-even\"><div class=\"inner-padding\"><a id=\"tips\"><\/a><h2 class=\"subcontent-main-title foreground-primary foreground-primary\">Les six r\u00e8gles de comportement en cas d\u2019urgence <\/h2><div class=\"clues-inner-table clues-count-even\"><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 1-agir-sans-se-mettre-en-danger\"><h3 class=\"clue-title background-primary foreground-title\">1. Agir sans se mettre en danger<\/h3><p><!-- wp:paragraph --><\/p>\n<p>Il peut en aller de votre vie\u2009: personne ne vous demande de devenir \u00e0 votre tour une victime en vous portant au secours d\u2019une victime. En revanche, n\u2019h\u00e9sitez pas \u00e0 encourir un <em>risque non physique,<\/em> et \u00e0 vous ridiculiser, si d\u2019aventure vous tombiez sous l\u2019\u0153il d\u2019une cam\u00e9ra cach\u00e9e\u2009! (Si r\u00e9ellement la sc\u00e8ne a \u00e9t\u00e9 enregistr\u00e9e par une cam\u00e9ra de vid\u00e9osurveillance, vous avez le droit d\u2019en interdire la diffusion\u2009; la PSC l\u2019explique dans sa brochure <a href=\"https:\/\/www.skppsc.ch\/fr\/download\/mon-image-agir-de-bon-droit\/\">Mon image\u2009: Agir de bon droit<\/a>.)<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 2-demander-de-laide\"><h3 class=\"clue-title background-primary foreground-title\">2. Demander de l\u2019aide<\/h3><p><!-- wp:paragraph --><\/p>\n<p>Adressez-vous imm\u00e9diatement aux autres personnes pr\u00e9sentes, demandez-leur comment elles voient la situation. Vous lutterez ainsi efficacement contre les deux pi\u00e8ges psychiques d\u00e9crits plus haut que sont la \u00ab\u2009diffusion des responsabilit\u00e9s\u2009\u00bb et l\u2019\u2009\u00ab\u2009ignorance pluraliste\u2009\u00bb et trouverez probablement tr\u00e8s vite d\u2019autres personnes pr\u00eates \u00e0 s\u2019interposer.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 3-observer-attentivement\"><h3 class=\"clue-title background-primary foreground-title\">3. Observer attentivement<\/h3><p><!-- wp:paragraph --><\/p>\n<p>Que se passe-t-il\u2009? Qui a dit quoi, qui a frapp\u00e9 le premier\u2009? Pour \u00e9tablir la responsabilit\u00e9 d\u2019un auteur de violence, il faut pouvoir l\u2019identifier avec certitude et \u00eatre capable de reconstituer les faits. D\u2019o\u00f9 l\u2019importance d\u2019observer chaque d\u00e9tail\u2009: c\u2019est ce qui fera toute la valeur de votre d\u00e9claration de t\u00e9moin.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 4-appeler-a-laide\"><h3 class=\"clue-title background-primary foreground-title\">4. Appeler \u00e0 l\u2019aide<\/h3><p><!-- wp:paragraph --><\/p>\n<p>Si l\u2019escalade menace ou que la bagarre fait d\u00e9j\u00e0 rage, alertez imm\u00e9diatement la police en composant le<strong> 117\u2009!<\/strong> Cette r\u00e8gle est aussi valable pour la violence domestique\u2009: n\u2019ignorez pas les bruits de coups, les cris de douleur ou les pleurs des enfants qui vous parviennent de l\u2019appartement voisin. Peu importe qu\u2019ils vous saluent tous poliment le lendemain dans l\u2019escalier, agissez\u2009! Pour les victimes, mieux vaut, c\u2019est s\u00fbr, trop en faire que pas assez. Dans le doute, appelez donc la police.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 5-soccuper-des-victimes\"><h3 class=\"clue-title background-primary foreground-title\">5. S\u2019occuper des victimes<\/h3><p><!-- wp:paragraph --><\/p>\n<p>M\u00eame si vous n\u2019\u00eates pas en mesure d\u2019intervenir, ne quittez pas les lieux, attendez dans les parages pour aider la victime, d\u00e8s que les malfaiteurs seront partis. Les gestes \u00e9l\u00e9mentaires de premiers secours vous seront bien utiles, l\u00e0 comme ailleurs.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><div class=\"clue-item clues-count-even clues-count-6 background-faded\"><div class=\"clue 6-faire-une-declaration-de-temoin\"><h3 class=\"clue-title background-primary foreground-title\">6. Faire une d\u00e9claration de t\u00e9moin<\/h3><p><!-- wp:paragraph --><\/p>\n<p>Lorsque la police sera sur les lieux, dites que vous avez \u00e9t\u00e9 t\u00e9moin. Peut-\u00eatre avez-vous observ\u00e9 un d\u00e9tail d\u00e9terminant qui permettra de remonter jusqu\u2019\u00e0 l\u2019auteur du m\u00e9fait. La victime vous en sera reconnaissante, la meilleure th\u00e9rapie pour elle \u00e9tant la punition du coupable.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n<blockquote class=\"wp-block-quote foreground-primary\">\n<p>\u00ab\u2009Oppose-toi aux premiers maux\u2009!\u2009\u00bb<\/p>\n<cite>Ovide, 43 av. J.-C.\u201317 apr\u00e8s J.-C.<\/cite><\/blockquote>\n\n\n\n<p>La coh\u00e9sion sociale, l\u2019attention \u00e0 l\u2019autre et le respect ne sont pas des valeurs qui se d\u00e9cr\u00e8tent. En fin de compte, chaque \u00eatre humain est responsable de sa conduite envers sa famille, ses voisins et toutes les autres personnes de son entourage. <strong>On ne perd rien en s\u2019engageant pour plus de justice et d\u2019\u00e9quit\u00e9 et en aidant les plus faibles.<\/strong><\/p>\n\n\n\n<p><strong>Sans courage civique, nous avons tous de mauvaises cartes en main. Donc, n\u2019h\u00e9sitez pas. Interposez-vous\u2009!<\/strong><\/p>\n\n\n\n<\/div><\/div><div class=\"default-container content-part replaced-hr\"><div class=\"inner-padding\">\n\n\n\n<h2 class=\"wp-block-heading foreground-primary\">Informations compl\u00e9mentaires, offres d\u2019aide, adresses de contact, signalement<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Violence domestique<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.skppsc.ch\/fr\/sujets\/violence\/violence-domestique\/\">Infos de la PSC<\/a><br><a href=\"https:\/\/www.youtube.com\/watch?v=B_c0f0ZtjOI&amp;t=4s\" target=\"_blank\" rel=\"noreferrer noopener\">Vid\u00e9o de la PSC<\/a><br><a href=\"https:\/\/www.aide-aux-victimes.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aide aux victimes en Suisse<\/a> | <a href=\"tel:+41142\">T\u00e9l. 142<\/a><br><a href=\"https:\/\/apea-en-bref.ch\" target=\"_blank\" rel=\"noreferrer noopener\">Autorit\u00e9 de protection de l\u2019enfant et de l\u2019adulte (APEA)<\/a><br><a href=\"https:\/\/csvd.ch\/csvd\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conf\u00e9rence Suisse contre la Violence Domestique (CSVD)<\/a><br><a href=\"https:\/\/www.ebg.admin.ch\/fr\/violence-a-legard-des-femmes-et-violence-domestique\" target=\"_blank\" rel=\"noreferrer noopener\">Bureau f\u00e9d\u00e9ral de l\u2019\u00e9galit\u00e9 entre femmes et hommes (BFEG)<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mobbing<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.skppsc.ch\/fr\/sujets\/internet\/cyberharcelement\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infos de la PSC<\/a><br><a href=\"https:\/\/www.youtube.com\/watch?v=_TVGwR2J9Qs&amp;t=2s\" target=\"_blank\" rel=\"noreferrer noopener\">Vid\u00e9o de la PSC<\/a><br><a href=\"https:\/\/www.skppsc.ch\/fr\/download\/brigades-des-mineurs\/\" target=\"_blank\" rel=\"noreferrer noopener\">Annuaire des brigades des mineurs des corps de police en Suisse<\/a><br><a href=\"https:\/\/www.147.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">147.ch<\/a>, Pro Juventute<br><a href=\"https:\/\/www.jeunesetmedias.ch\/themes\/cyberharcelement-ridiculiser-et-demolir\" target=\"_blank\" rel=\"noreferrer noopener\">Jeunes et m\u00e9dias<\/a>, Plateforme nationale de promotion des comp\u00e9tences num\u00e9riques<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Harc\u00e8lement sexuel<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.skppsc.ch\/fr\/sujets\/violence-sexuelle\/violence-sexuelle-adultes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infos de la PSC<\/a><br><a href=\"https:\/\/www.aide-aux-victimes.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aide aux victimes en Suisse<\/a> | <a href=\"tel:+41142\">T\u00e9l. 142<\/a><br><a href=\"https:\/\/belaestigt.ch\/ich-wuensche-beratung-francais\/\" target=\"_blank\" rel=\"noreferrer noopener\">belaestigt.ch<\/a>, Service de conseil pour les victimes de harc\u00e8lement sexuel sur le lieu de travail<br><a href=\"https:\/\/www.ebg.admin.ch\/fr\/harcelement-sexuel-sur-le-lieu-de-travail\" target=\"_blank\" rel=\"noreferrer noopener\">Bureau f\u00e9d\u00e9ral de l\u2019\u00e9galit\u00e9 entre femmes et hommes (BFEG)<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Discours de haine<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.skppsc.ch\/fr\/download\/discours-de-haine-crime-de-haine\/\">Infos de la PSC<\/a><br><a href=\"https:\/\/www.reportonlineracism.ch\/f101.html\" target=\"_blank\" rel=\"noreferrer noopener\">Plateforme de signalement des discours de haine racistes sur Internet<\/a><br><a href=\"https:\/\/stophatespeech.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stop Hate Speech<\/a><br><a href=\"https:\/\/www.jeunesetmedias.ch\/themes\/discrimination-et-discours-de-haine-en-ligne\" target=\"_blank\" rel=\"noreferrer noopener\">Jeunes et m\u00e9dias<\/a>, Plateforme nationale de promotion des comp\u00e9tences num\u00e9riques<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Racisme<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.reportonlineracism.ch\/f101.html\" target=\"_blank\" rel=\"noreferrer noopener\">Plateforme de signalement des discours de haine racistes sur Internet<\/a><br><a href=\"https:\/\/www.edi.admin.ch\/edi\/fr\/home\/fachstellen\/frb.html\" target=\"_blank\" rel=\"noreferrer noopener\">Service de lutte contre le racisme<\/a>, D\u00e9partement f\u00e9d\u00e9ral de l\u2019int\u00e9rieur (DFI)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vandalisme<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.skppsc.ch\/fr\/download\/spruehende-kreativitaet-francais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Infos de la PSC<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Informations g\u00e9n\u00e9rales<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.gra.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.gra.ch<\/a>\u2009: La Fondation contre le racisme et l\u2019anti\u00ads\u00e9mitisme (GRA) s\u2019engage en faveur des droits de l\u2019homme et du maintien de la d\u00e9mocratie selon la conception propre \u00e0 la Suisse. La Fondation s\u2019engage pour la tol\u00e9rance et contre toute forme de discrimination.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ciao.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.ciao.ch<\/a>\u2009: Ce site est g\u00e9r\u00e9 par l\u2019Association romande CIAO. D\u00e9di\u00e9 aux jeunes de Suisse romande \u00e2g\u00e9s de 11 \u00e0 20 ans, il contient de nombreuses infos pour les jeunes sur le sujet du courage civique, de la sexualit\u00e9, du racisme et des valeurs d\u00e9mocratiques.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.feel-ok.ch\/fr_CH\/ecole\/sujets\/sujets.cfm\" target=\"_blank\" rel=\"noreferrer noopener\">www.feel-ok.ch<\/a> : Con\u00e7ue en priorit\u00e9 pour \u00eatre utilis\u00e9e dans le contexte scolaire, cette plateforme contient des contenus de promotion de la sant\u00e9 \u00e0 l\u2019adresse des jeunes et des outils pratiques pour les traiter.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formations<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/ncbi.ch\/fr\/page-daccueil\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.ncbi.ch\u2009<\/a>: L\u2019association \u00ab\u2009National Coalition Building Institute Suisse\u2009\u00bb s\u2019engage contre la discrimination (racisme, x\u00e9nophobie, antis\u00e9mitisme, sexisme, homophobie, etc.) et contre la violence, en animant des ateliers et des projets en divers lieux de Suisse.<\/p>\n\n\n\n<p><a href=\"https:\/\/non-violence.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.non-violence.ch<\/a>\u2009: Pr\u00e9venir la violence et r\u00e9soudre les conflits de mani\u00e8re non-violente demande un apprentissage. Le Centre pour l\u2019action non-violente (CENAC) propose ainsi un programme de formation \u00e0 la r\u00e9solution non-violente des conflits, des formations \u00e0 la carte r\u00e9pondant \u00e0 des demandes sp\u00e9cifiques et des ateliers de communication non violente \u00e0 Gen\u00e8ve.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Protection des minorit\u00e9s<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/www.gms-minderheiten.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.gms-minderheiten.ch<\/a>\u2009: La Soci\u00e9t\u00e9 pour les minorit\u00e9s en Suisse est une association politiquement ind\u00e9pendante et confessionnellement neutre avec un grand nombre d\u2019activit\u00e9s et de terrains d\u2019action. La GMS lutte pour les droits et la protection des minorit\u00e9s. (site seulement en allemand)<\/p>\n\n\n\n<p><a href=\"https:\/\/non-violence.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.non-violence.ch<\/a>\u2009: Le Centre pour l\u2018action non-violente (CENAC) a pour mission de promouvoir la non-violence en Suisse romande. La non-violence, c\u2019est d\u2019abord le respect de soi, d\u2019autrui et de l\u2019environnement. C\u2019est aussi ne pas rester passif devant les injustices.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ekr.admin.ch\/f112.html\" target=\"_blank\" rel=\"noreferrer noopener\">www.ekr.admin.ch<\/a>\u2009: La Commission f\u00e9d\u00e9rale contre le racisme (CFR) est une commission extraparlementaire institu\u00e9e par le Conseil f\u00e9d\u00e9ral pour mettre en \u0153uvre la Convention internationale sur l\u2019\u00e9limination de toutes les formes de discrimination raciale (CERD).<\/p>\n\n\n\n<p><a href=\"https:\/\/skmr.ch\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.csdh.ch<\/a>\u2009: Le centre suisse de comp\u00e9tences pour les droits humains (CSDH) est un projet pilote mandat\u00e9 par la Conf\u00e9d\u00e9ration. Il a pour t\u00e2che d\u2019encourager la mise en \u0153uvre des obligations internationales de la Suisse en mati\u00e8re de droits humains ainsi que de conseiller et de soutenir les autorit\u00e9s \u00e0 tous les niveaux, la soci\u00e9t\u00e9 civile et le monde \u00e9conomique.<\/p>\n<\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Cette rubrique Internet traite d\u2019un sujet important\u2009: le courage civique. Important, parce qu\u2019il touche toutes les citoyennes et tous les citoyens qui souhaitent une coexistence pacifique, au sein d\u2019une soci\u00e9t\u00e9 d\u00e9mocratique et respectueuse de l\u2019\u00c9tat de droit \u2013 et qui souhaitent continuer \u00e0 vivre ainsi. <\/p>\n","protected":false},"author":349,"featured_media":0,"parent":2165,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"showSharingButtons":false,"skp-theme-color":"seven","_subtitle":"","alternative_title":"","seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"C33AJ0oeBMQ","notes":"","redirectToPostId":0,"skp-further-information":"","hideTile":false,"pageType":"","editor_notices":[],"footnotes":""},"topic":[],"class_list":["post-2166","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/2166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/comments?post=2166"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/2166\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/pages\/2165"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/media?parent=2166"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/topic?post=2166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}