{"id":2431,"date":"2025-09-15T07:07:21","date_gmt":"2025-09-15T05:07:21","guid":{"rendered":"https:\/\/www.skppsc.ch\/fr\/?p=2431"},"modified":"2025-09-15T07:08:29","modified_gmt":"2025-09-15T05:08:29","slug":"communique-de-presse-ensemble-sans-violence-sexuelle","status":"publish","type":"post","link":"https:\/\/www.skppsc.ch\/fr\/communique-de-presse-ensemble-sans-violence-sexuelle\/","title":{"rendered":"Communiqu\u00e9 de presse: Ensemble sans violence sexuelle"},"content":{"rendered":"<html><body><div class=\"default-container content-part\"><div class=\"inner-padding\">\n<p><em>Berne, le 15\u00a0septembre 2025. La violence sexuelle, qui porte atteinte aux droits humains fondamentaux, n\u2019\u00e9pargne malheureusement aucun domaine de notre soci\u00e9t\u00e9. Elle peut survenir partout\u00a0: \u00e0 la maison, dans l\u2019espace public et sur le lieu de travail. Dans ce contexte et dans le cadre du Plan d\u2019action national pour la mise en \u0153uvre de la Convention d\u2019Istanbul 2022-2026, la Pr\u00e9vention Suisse de la Criminalit\u00e9 (PSC) a \u00e9t\u00e9 mandat\u00e9e pour r\u00e9aliser une campagne de sensibilisation. Cette campagne compl\u00e8te de mani\u00e8re pertinente la campagne nationale de pr\u00e9vention contre la violence domestique, sexualis\u00e9e et de genre qui sera lanc\u00e9e en novembre 2025 par le Bureau f\u00e9d\u00e9ral de l\u2019\u00e9galit\u00e9 entre femmes et hommes (BFEG).<\/em><\/p>\n\n\n\n<p>Aujourd\u2019hui, la PSC et les polices cantonales et municipales lancent la <a href=\"https:\/\/www.skppsc.ch\/fr\/projets\/ensemble-sans-violence-sexuelle\/\" target=\"_blank\" rel=\"noreferrer noopener\">campagne de sensibilisation nationale \u00ab\u00a0Ensemble sans violence sexuelle \u00bb<\/a> qui durera jusqu\u2019\u00e0 la fin du mois d\u2019octobre. Cette campagne met l\u2019accent sur la violence sexuelle sous toutes ses formes \u2013 des agressions verbales aux contacts physiques non d\u00e9sir\u00e9s jusqu\u2019aux contraintes sexuelles et aux viols. Elle a pour objectif de contribuer \u00e0 une prise de conscience g\u00e9n\u00e9rale\u00a0: la violence sexuelle est malheureusement une r\u00e9alit\u00e9 quotidienne dans notre soci\u00e9t\u00e9\u00a0; nous devons unir nos forces pour contrer ce ph\u00e9nom\u00e8ne. En effet, si nous voulons bien vivre ensemble, nous devons commencer par bannir toute forme de violence sexuelle\u00a0!.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Omnipr\u00e9sence de la violence sexuelle<\/strong><\/strong><\/h3>\n\n\n\n<p>La violence sexuelle peut survenir partout, \u00e0 la maison, dans l\u2019espace public et sur le lieu de travail. Les exemples sont multiples\u00a0: il y a l\u2019homme qui, \u00e0 la maison, contraint sa partenaire \u00e0 des actes sexuels par la violence ou en la mena\u00e7ant de violence\u00a0; il y a ceux qui profitent de l\u2019exigu\u00eft\u00e9 des transports publics aux heures de pointe pour pratiquer des attouchements non consentis\u00a0; il y a le sup\u00e9rieur qui s\u2019assied \u00e0 c\u00f4t\u00e9 de son employ\u00e9e en se collant \u00e0 elle pour l\u2019aider \u00e0 r\u00e9soudre un probl\u00e8me informatique, et qui, l\u2019air de rien, lui fr\u00f4le le genou. Ces diff\u00e9rents cas de figure montrent \u00e0 quel point l\u2019angle d\u2019attaque de notre campagne de sensibilisation doit viser large.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Campagne de sensibilisation et label de qualit\u00e9<\/strong><\/strong><\/h3>\n\n\n\n<p>Nous avons cr\u00e9\u00e9 un label de qualit\u00e9, sur le mod\u00e8le de ce qui se fait dans le secteur de la sant\u00e9 et de la beaut\u00e9, qui est la pi\u00e8ce ma\u00eetresse de notre campagne\u00a0; un label qui atteste d\u2019une r\u00e9alit\u00e9 sociale qui n\u2019existe certes pas (encore), mais qu\u2019ensemble nous aspirons \u00e0 cr\u00e9er. A l\u2019instar des produits de sant\u00e9 et de beaut\u00e9, ce label mentionne les ingr\u00e9dients n\u00e9fastes absents de notre projet de soci\u00e9t\u00e9 saine et les ingr\u00e9dients de qualit\u00e9 qui seront n\u00e9cessaires pour r\u00e9aliser ce projet. Une soci\u00e9t\u00e9 labellis\u00e9e \u00ab\u00a0sans violence sexuelle\u00a0\u00bb doit pouvoir garantir \u00e0 100\u00a0% le respect mutuel et l\u2019absence d\u2019abus sexuels\u00a0: c\u2019est le gage d\u2019une vie sociale saine.<\/p>\n\n\n\n<p>Ce label sera imprim\u00e9 sur diff\u00e9rents supports\u00a0: trois affiches pr\u00e9sentant des situations du quotidien susceptibles de d\u00e9g\u00e9n\u00e9rer en violence sexuelle, des cartes postales comportant des recommandations d\u2019action, des autocollants et des broches ainsi que des supports num\u00e9riques permettront de diffuser largement ce label dans l\u2019espace public et les transports en commun, dans les centres de conseil et sur les plateformes m\u00e9diatiques en ligne. Plus d\u2019informations sur le site Internet <a href=\"http:\/\/www.sans-violence-sexuelle.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.sans-violence-sexuelle.ch<\/a>.<\/p>\n\n\n\n<p>Nous regroupons sous le terme de\u00a0\u00ab\u00a0violence sexuelle\u00a0\u00bbtoute forme d\u2019agression et d\u2019atteinte sexuelle, par la parole ou par le geste, qu\u2019elle soit insidieuse ou ouvertement violente. Cela inclut \u00e9galement la notion de \u00ab violence sexualis\u00e9e \u00bb dont l\u2019objectif premier est d\u2019humilier la victime, de la contr\u00f4ler et d\u2019exercer un pouvoir sur elle.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Large partenariat<\/strong><\/strong><\/h3>\n\n\n\n<p>Cette campagne de sensibilisation nationale a \u00e9t\u00e9 d\u00e9velopp\u00e9e avec le concours d\u2019organisations sp\u00e9cialis\u00e9es et partenaires de premier plan, parmi lesquelles l\u2019Aide aux victimes en Suisse, le Bureau f\u00e9d\u00e9ral de l\u2019\u00e9galit\u00e9 entre femmes et hommes BFEG, le Centre universitaire romand de m\u00e9decine l\u00e9gale CURML \u2013 Gen\u00e8ve et Lausanne, la Conf\u00e9rence des directrices et directeurs cantonaux des affaires sociales CDAS, la Conf\u00e9rence suisse contre la violence domestique CSVD, la Conf\u00e9rence suisse des d\u00e9l\u00e9gu\u00e9es et des d\u00e9l\u00e9gu\u00e9s \u00e0 l\u2019\u00e9galit\u00e9 CSDE, l\u2019Organisation fa\u00eeti\u00e8re suisse pour la pr\u00e9vention de la violence Solvio, ainsi que ProCoRe Suisse. Le BFEG soutient la campagne au moyen d\u2019aides financi\u00e8res.<\/p>\n\n\n<\/div><\/div><div class=\"content-part pdf-download-wrapper\"><div class=\"pdf-download-wrapper\"><a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/communique-de-presse.pdf\" download target=\"_blank\" class=\"pdf-download with-button-text\"><span class=\"skp-download-pdf pdf-download-icon\"><\/span><span class=\"download-button-text\">Communiqu\u00e9 de presse<\/span><\/a><\/div><\/div><div class=\"default-container content-part\"><div class=\"inner-padding\">\n\n\n<h5 class=\"wp-block-heading\">T\u00e9l\u00e9charger le mat\u00e9riel de campagne<\/h5>\n\n\n<ul class=\"download-list\"><li class=\"download-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_maison.pdf\" target=\"_blank\" class=\"download-list-item-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_maison-pdf-106x150.jpg\" class=\"download-list-item-preview\" alt=\"Affiche \u00ab\u00e0 la maison\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-list-item-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-link-text\">Affiche \u00ab\u00e0 la maison\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-meta\">PDF | 271.67 KB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/li><li class=\"download-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_espace_public.pdf\" target=\"_blank\" class=\"download-list-item-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_espace_public-pdf-106x150.jpg\" class=\"download-list-item-preview\" alt=\"Affiche \u00abdans l'espace public\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-list-item-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-link-text\">Affiche \u00abdans l\u2019espace public\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-meta\">PDF | 248.35 KB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/li><li class=\"download-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_lieu_de_travail.pdf\" target=\"_blank\" class=\"download-list-item-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/affiche_lieu_de_travail-pdf-106x150.jpg\" class=\"download-list-item-preview\" alt=\"Affiche \u00absur le lieu de travail\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-list-item-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-link-text\">Affiche \u00absur le lieu de travail\u00bb \u2013 \u00abEnsemble sans violence sexuelle\u00bb<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-meta\">PDF | 220.93 KB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/li><li class=\"download-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/alle_bereiche_label_fr-scaled.jpg\" target=\"_blank\" class=\"download-list-item-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/alle_bereiche_label_fr-150x150.jpg\" class=\"download-list-item-preview\" alt=\"Image avec les trois domaines\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-list-item-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-link-text\">Image avec les trois domaines<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-meta\">JPG | 366.67 KB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/li><li class=\"download-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/label-de-qualite-ensemble-sans-violence-sexuelle.png\" target=\"_blank\" class=\"download-list-item-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.skppsc.ch\/fr\/wp-content\/uploads\/sites\/5\/2025\/09\/label-de-qualite-ensemble-sans-violence-sexuelle-150x150.png\" class=\"download-list-item-preview\" alt=\"Label de qualit\u00e9 \u00abEnsemble sans violence sexuelle\u00bb\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"download-list-item-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-link-text\">Label de qualit\u00e9 \u00abEnsemble sans violence sexuelle\u00bb<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"download-list-item-meta\">PNG | 89.37 KB<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/a> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/li><\/ul>\n\n\n<p>Contact : <a href=\"&#x6d;&#x61;&#105;l&#x74;&#x6f;&#58;&#109;e&#x64;&#x69;&#97;&#64;s&#x6b;&#x70;&#112;sc&#x2e;&#x63;&#104;\">&#x6d;e&#x64;&#105;&#x61;&#64;&#x73;&#x6b;p&#x70;&#115;&#x63;&#46;&#x63;&#104;<\/a><\/p>\n\n\n\n<p>Plus d\u2019informations : <a href=\"https:\/\/www.skppsc.ch\/fr\/projets\/ensemble-sans-violence-sexuelle\/\" data-type=\"page\" data-id=\"1261\" target=\"_blank\" rel=\"noreferrer noopener\">www.sans-violence-sexuelle.ch<\/a><\/p>\n<\/div><\/div><\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>Berne, le 15\u00a0septembre 2025. La violence sexuelle, qui porte atteinte aux droits humains fondamentaux, n\u2019\u00e9pargne malheureusement aucun domaine de notre soci\u00e9t\u00e9. Elle peut survenir partout\u00a0: \u00e0 la maison, dans l\u2019espace public et sur le lieu de travail. Dans ce contexte et dans le cadre du Plan d\u2019action national pour la mise en \u0153uvre de la [&hellip;]<\/p>\n","protected":false},"author":385,"featured_media":2421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"showSharingButtons":false,"skp-theme-color":"nine","_subtitle":"","alternative_title":"","seoDescription":"","seoKeywords":"","seoTitle":"","featuredVideoEmbedCode":"","featuredYoutubeVideoId":"","notes":"","redirectToPostId":0,"editor_notices":[],"footnotes":""},"categories":[98,97],"topic":[],"class_list":["post-2431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medias","category-nouveautes"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/posts\/2431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/users\/385"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/comments?post=2431"}],"version-history":[{"count":0,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/posts\/2431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/media\/2421"}],"wp:attachment":[{"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/media?parent=2431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/categories?post=2431"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.skppsc.ch\/fr\/wp-json\/wp\/v2\/topic?post=2431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}